{"id":15911,"date":"2019-12-08T09:00:00","date_gmt":"2019-12-08T08:00:00","guid":{"rendered":"http:\/\/www.soroptimisteurope.org\/?p=15911"},"modified":"2025-05-13T11:17:10","modified_gmt":"2025-05-13T09:17:10","slug":"porto-dabrigo-foyer-pour-victimes-de-violences-domestiques","status":"publish","type":"post","link":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/","title":{"rendered":"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques"},"content":{"rendered":"<h3>SI Club de Porto Invicta, Portugal<\/h3>\n<p>Depuis sa fondation par la Soroptimist Teresa Rosmaninho, le <strong>SI Club de Porto Invicta<\/strong> s\u2019est concentr\u00e9 sur l\u2019<strong>\u00e9galit\u00e9 des sexes et la violence contre les femmes <\/strong>et les enfants, et plus particuli\u00e8rement dans un cadre domestique. Les membres du Club g\u00e8rent ainsi quotidiennement un centre d\u2019accueil appel\u00e9 \u00ab\u00a0Porto d\u2019Abrigo\u00a0\u00bb pour des femmes et leurs enfants, victimes de violences domestiques. Quand Leida, m\u00e8re de deux fils de 6 et 16 ans, est arriv\u00e9e au centre, elle a tout de suite pens\u00e9\u00a0:\u00a0\u00ab\u00a0La vie ici sera vraiment meilleure\u00a0!\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"200\"><\/td>\n<td width=\"200\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-15905\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/picture2.jpg\" alt=\"\" width=\"251\" height=\"300\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/picture2.jpg 633w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/picture2-251x300.jpg 251w\" sizes=\"(max-width: 251px) 100vw, 251px\" \/><\/td>\n<td width=\"200\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Le centre offre aux victimes la possibilit\u00e9 de b\u00e9n\u00e9ficier d\u2019un soutien social, psychologique et \u00e9ducatif. En effet, la majorit\u00e9 des femmes, accueillies dans le centre, ont un faible niveau \u00e9ducatif. Des outils pour faire face au futur leur sont aussi propos\u00e9s et on les aide \u00e0 trouver des foyers transitoires, afin qu\u2019elles puissent mener une vie ind\u00e9pendante, loin de toute violence. Les victimes de violence domestique doivent souvent quitter leur maison et perdent tout. Elles doivent apprendre \u00e0 vivre avec de nouvelles personnes, qui vivent des souffrances similaires, et essayer de se reconstruire en trouvant \u00e9ventuellement un nouveau travail, une nouvelle \u00e9cole pour leur enfant, un nouveau logement, etc.<\/p>\n<p>Gr\u00e2ce \u00e0 Catarina, fille de la fondatrice, et \u00e0 l&rsquo;\u00e9quipe du foyer &#8211; compos\u00e9e de sept membres -le centre a permis d\u2019accueillir 148 femmes (moyenne d\u2019\u00e2ge de 36 ans) et 179 enfants (moyenne d\u2019\u00e2ge de 6 ans) depuis l\u2019ouverture de cette structure. La dur\u00e9e moyenne des s\u00e9jours est de 7 mois et demi.<\/p>\n<div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/shelter.jpg\" alt=\"shelter\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SI Club de Porto Invicta, Portugal Depuis sa fondation par la Soroptimist Teresa Rosmaninho, le SI Club de Porto Invicta s\u2019est concentr\u00e9 sur l\u2019\u00e9galit\u00e9 des sexes et la violence contre [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":37198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[106,112],"tags":[78],"class_list":["post-15911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-violence-against-women","tag-violence-against-women"],"acf":{"article_photo_de_couverture":{"ID":15901,"id":15901,"title":"Close up horizontal image of female and child hands holding white paper house on gray background. Family home and real estate concept. Flat lay, copy space","filename":"istock-1185738895.jpg","filesize":4092413,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/istock-1185738895.jpg","link":"https:\/\/www.soroptimisteurope.org\/fr\/close-up-horizontal-image-of-female-and-child-hands-holding-white-paper-house-on-gray-background-family-home-and-real-estate-concept-flat-lay-copy-space-2-2\/","alt":"","author":"3","description":"","caption":"Close up horizontal image of female and child hands holding white paper house on gray background. Family home and real estate concept. Flat lay, copy space","name":"close-up-horizontal-image-of-female-and-child-hands-holding-white-paper-house-on-gray-background-family-home-and-real-estate-concept-flat-lay-copy-space-2-2","status":"inherit","uploaded_to":0,"date":"2019-12-06 08:23:57","modified":"2019-12-06 08:34:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.soroptimisteurope.org\/wp-content\/plugins\/media-library-assistant\/images\/crystal\/image.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/istock-1185738895-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/istock-1185738895-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/istock-1185738895-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/istock-1185738895-1024x683.jpg","large-width":800,"large-height":534,"1536x1536":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/istock-1185738895-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/istock-1185738895-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365}},"article_chapeau":"","article_contenu":[{"article_titre_du_paragraphe":"SI Club de Porto Invicta, Portugal","article_paragraphe":"<p>Depuis sa fondation par la Soroptimist Teresa Rosmaninho, le <strong>SI Club de Porto Invicta<\/strong> s\u2019est concentr\u00e9 sur l\u2019<strong>\u00e9galit\u00e9 des sexes et la violence contre les femmes <\/strong>et les enfants, et plus particuli\u00e8rement dans un cadre domestique. Les membres du Club g\u00e8rent ainsi quotidiennement un centre d\u2019accueil appel\u00e9 \u00ab\u00a0Porto d\u2019Abrigo\u00a0\u00bb pour des femmes et leurs enfants, victimes de violences domestiques. Quand Leida, m\u00e8re de deux fils de 6 et 16 ans, est arriv\u00e9e au centre, elle a tout de suite pens\u00e9\u00a0:\u00a0\u00ab\u00a0La vie ici sera vraiment meilleure\u00a0!\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"200\"><\/td>\n<td width=\"200\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-15905\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/picture2-251x300.jpg\" alt=\"\" width=\"251\" height=\"300\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/picture2-251x300.jpg 251w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/picture2.jpg 633w\" sizes=\"(max-width: 251px) 100vw, 251px\" \/><\/td>\n<td width=\"200\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Le centre offre aux victimes la possibilit\u00e9 de b\u00e9n\u00e9ficier d\u2019un soutien social, psychologique et \u00e9ducatif. En effet, la majorit\u00e9 des femmes, accueillies dans le centre, ont un faible niveau \u00e9ducatif. Des outils pour faire face au futur leur sont aussi propos\u00e9s et on les aide \u00e0 trouver des foyers transitoires, afin qu\u2019elles puissent mener une vie ind\u00e9pendante, loin de toute violence. Les victimes de violence domestique doivent souvent quitter leur maison et perdent tout. Elles doivent apprendre \u00e0 vivre avec de nouvelles personnes, qui vivent des souffrances similaires, et essayer de se reconstruire en trouvant \u00e9ventuellement un nouveau travail, une nouvelle \u00e9cole pour leur enfant, un nouveau logement, etc.<\/p>\n<p>Gr\u00e2ce \u00e0 Catarina, fille de la fondatrice, et \u00e0 l&rsquo;\u00e9quipe du foyer &#8211; compos\u00e9e de sept membres -le centre a permis d\u2019accueillir 148 femmes (moyenne d\u2019\u00e2ge de 36 ans) et 179 enfants (moyenne d\u2019\u00e2ge de 6 ans) depuis l\u2019ouverture de cette structure. La dur\u00e9e moyenne des s\u00e9jours est de 7 mois et demi.<\/p>\n","article_media_image":{"ID":15903,"id":15903,"title":"shelter","filename":"shelter.jpg","filesize":1700834,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/shelter.jpg","link":"https:\/\/www.soroptimisteurope.org\/fr\/shelter-2\/","alt":"","author":"3","description":"","caption":"","name":"shelter-2","status":"inherit","uploaded_to":0,"date":"2019-12-06 08:24:32","modified":"2019-12-06 08:34:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.soroptimisteurope.org\/wp-content\/plugins\/media-library-assistant\/images\/crystal\/image.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/shelter-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/shelter-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/shelter-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/shelter-1024x768.jpg","large-width":800,"large-height":600,"1536x1536":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/shelter-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/shelter-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536}},"article_media_video":""}],"article_trombinoscope":false,"article_video":"","article_evenements_sociaux":false,"article_auteur_texte":"","article_nom_contact":"","article_email_contact":"","article_numero_contact":"","article_documents":false,"article_actualites_liees":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Porto d\u2019Abrigo: foyer pour victimes de violences domestiques - Soroptimist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques - Soroptimist\" \/>\n<meta property=\"og:description\" content=\"SI Club de Porto Invicta, Portugal Depuis sa fondation par la Soroptimist Teresa Rosmaninho, le SI Club de Porto Invicta s\u2019est concentr\u00e9 sur l\u2019\u00e9galit\u00e9 des sexes et la violence contre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Soroptimist\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-08T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T09:17:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1185738895-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Virginie Racine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Virginie Racine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/\"},\"author\":{\"name\":\"Virginie Racine\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"headline\":\"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques\",\"datePublished\":\"2019-12-08T08:00:00+00:00\",\"dateModified\":\"2025-05-13T09:17:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/\"},\"wordCount\":276,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/istock-1185738895-scaled.jpg\",\"keywords\":[\"Violence Against Women\"],\"articleSection\":[\"News\",\"Violence Against Women\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/\",\"name\":\"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques - Soroptimist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/istock-1185738895-scaled.jpg\",\"datePublished\":\"2019-12-08T08:00:00+00:00\",\"dateModified\":\"2025-05-13T09:17:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/istock-1185738895-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/istock-1185738895-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/\",\"name\":\"Soroptimist\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\",\"name\":\"Virginie Racine\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/author\\\/adminsorop2k21\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques - Soroptimist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques - Soroptimist","og_description":"SI Club de Porto Invicta, Portugal Depuis sa fondation par la Soroptimist Teresa Rosmaninho, le SI Club de Porto Invicta s\u2019est concentr\u00e9 sur l\u2019\u00e9galit\u00e9 des sexes et la violence contre [&hellip;]","og_url":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/","og_site_name":"Soroptimist","article_published_time":"2019-12-08T08:00:00+00:00","article_modified_time":"2025-05-13T09:17:10+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1185738895-scaled.jpg","type":"image\/jpeg"}],"author":"Virginie Racine","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Virginie Racine","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/#article","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/"},"author":{"name":"Virginie Racine","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"headline":"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques","datePublished":"2019-12-08T08:00:00+00:00","dateModified":"2025-05-13T09:17:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/"},"wordCount":276,"commentCount":0,"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1185738895-scaled.jpg","keywords":["Violence Against Women"],"articleSection":["News","Violence Against Women"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/","url":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/","name":"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques - Soroptimist","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/#primaryimage"},"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1185738895-scaled.jpg","datePublished":"2019-12-08T08:00:00+00:00","dateModified":"2025-05-13T09:17:10+00:00","author":{"@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"breadcrumb":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/#primaryimage","url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1185738895-scaled.jpg","contentUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1185738895-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.soroptimisteurope.org\/fr\/porto-dabrigo-foyer-pour-victimes-de-violences-domestiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soroptimisteurope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Porto d\u2019Abrigo: foyer pour victimes de violences domestiques"}]},{"@type":"WebSite","@id":"https:\/\/www.soroptimisteurope.org\/#website","url":"https:\/\/www.soroptimisteurope.org\/","name":"Soroptimist","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soroptimisteurope.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619","name":"Virginie Racine","url":"https:\/\/www.soroptimisteurope.org\/fr\/author\/adminsorop2k21\/"}]}},"_links":{"self":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/15911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/comments?post=15911"}],"version-history":[{"count":0,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/15911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media\/37198"}],"wp:attachment":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media?parent=15911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/categories?post=15911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/tags?post=15911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}