{"id":16154,"date":"2019-12-19T10:00:38","date_gmt":"2019-12-19T09:00:38","guid":{"rendered":"http:\/\/www.soroptimisteurope.org\/?p=16154"},"modified":"2025-05-13T11:17:11","modified_gmt":"2025-05-13T09:17:11","slug":"women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle","status":"publish","type":"post","link":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/","title":{"rendered":"\u00ab Women Bridging Glass Cliff \u00bb &#8211; Conf\u00e9rence sur l&rsquo;\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle"},"content":{"rendered":"<p>Il est midi et je suis \u00e0 l&rsquo;a\u00e9roport de Copenhague\u00a0; je viens d&rsquo;arriver avec un vol d&rsquo;Islande. J&rsquo;attends qu&rsquo;Ulla Madsen, ancienne pr\u00e9sidente du SIE et directrice adjointe du Lobbying du SI, se joigne \u00e0 moi pour que nous nous rendions ensemble \u00e0 Istanbul afin de participer \u00e0 une <strong>conf\u00e9rence internationale sur l&rsquo;\u00e9galit\u00e9 des sexes dans la vie professionnelle<\/strong>, organis\u00e9e par <strong>SI Club Etiler<\/strong>. Nous sommes accueillies \u00e0 l&rsquo;a\u00e9roport d&rsquo;Istanbul par la pr\u00e9sidente fondatrice du Club, Emine Erdem, secr\u00e9taire et chauffeur, qui nous emm\u00e8ne dans sa belle maison, o\u00f9 nous profiterons d&rsquo;un accueil tout particulier pendant notre s\u00e9jour \u00e0 Istanbul.<\/p>\n<p>&nbsp;<\/p>\n<p>Cr\u00e9\u00e9 en 1988, le <strong>SI Club Etiler<\/strong> c\u00e9l\u00e8bre son <strong>30\u00e8me anniversaire<\/strong> sous le th\u00e8me \u00ab\u00a0Soroptimists Advocate Gender Equality (SAGE)\u00a0\u00bb. Il a sollicit\u00e9 et re\u00e7u une subvention pour le projet \u00ab\u00a0Grant Scheme for Grassroots Civil Society Organizations\u00a0\u00bb, qui est cofinanc\u00e9 par l&rsquo;Union europ\u00e9enne (UE) et la R\u00e9publique de Turquie.<\/p>\n<p>&nbsp;<\/p>\n<p>Le projet se subdivise en quatre parties:<\/p>\n<ul>\n<li>Les activit\u00e9s \u00ab\u00a0ChangEquality\u00a0\u00bb visant \u00e0 sensibiliser les \u00e9tudiants \u00e0 l&rsquo;\u00e9galit\u00e9 entre les sexes dans la vie professionnelle\u00a0;<\/li>\n<li>Les ambassadeurs du programme \u00ab\u00a0ChangEquality\u00a0\u00bb pour assurer la p\u00e9rennit\u00e9 du projet\u00a0;<\/li>\n<li>\u00ab\u00a0SAGE\u00a0\u00bb dans un programme de mentorat dans le milieu du travail, qui vise \u00e0 \u00e9quiper et \u00e0 autonomiser les femmes face aux obstacles qu&rsquo;elles rencontreront dans leur vie professionnelle\u00a0;<\/li>\n<li>\u00ab\u00a0Women Bridging Glass Cliff\u00a0\u00bb, conf\u00e9rence internationale sur l&rsquo;\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>En janvier 2019, le Club Etiler a contact\u00e9 les rectorats et des associations d&rsquo;\u00e9tudiants de diverses universit\u00e9s d&rsquo;Istanbul. Au lieu de faire des pr\u00e9sentations de sensibilisation, ses membres ont organis\u00e9 un jeu: \u00ab\u00a0ChangEquality\u00a0\u00bb, jou\u00e9 par 8 \u00e0 28 personnes. Ces derni\u00e8res sont invit\u00e9es \u00e0 r\u00e9pondre \u00e0 des questions et \u00e0 analyser des cas en groupes, ainsi qu\u2019\u00e0 formuler de nouvelles perspectives qui leur permettront ensuite de comprendre la situation actuelle, de discuter des in\u00e9galit\u00e9s, de repenser les probl\u00e8mes et proposer des solutions. Cela a d\u00e9j\u00e0 touch\u00e9 350 \u00e9tudiants.<\/p>\n<p>&nbsp;<\/p>\n<p>Pour donner suite aux r\u00e9sultats du jeu \u00ab\u00a0ChangEqualty\u00a0\u00bb, un programme a \u00e9t\u00e9 \u00e9labor\u00e9 dans le cadre duquel soixante personnes ont suivi une formation. Dix d&rsquo;entre elles ont \u00e9t\u00e9 nomm\u00e9es ambassadeurs \u00ab\u00a0ChangEquality\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>La troisi\u00e8me \u00e9tape a consist\u00e9 en une formation de mentorat de deux jours, en avril dernier, \u00e0 laquelle ont particip\u00e9 vingt-sept candidats mentors de huit clubs d&rsquo;Istanbul. Ensuite, une formation pour les personnes mentor\u00e9es a \u00e9t\u00e9 organis\u00e9e avec vingt-huit \u00e9tudiants. Vingt-cinq mentors et vingt-cinq mentor\u00e9s ont \u00e9t\u00e9 choisis pour six \u00e0 huit entrevues, pendant sept mois. Le programme a pour but de permettre aux mentors et aux mentor\u00e9s d&rsquo;acqu\u00e9rir des comp\u00e9tences; les personnes mentor\u00e9es acqui\u00e8rent ainsi les aptitudes n\u00e9cessaires pour faire face aux d\u00e9fis, auxquels ils peuvent \u00eatre confront\u00e9s dans leur vie professionnelle, tandis que les mentors apprennent \u00e0 renforcer leur capacit\u00e9 \u00e0 g\u00e9rer des processus structur\u00e9s, qui contribueront ensuite \u00e0 la valorisation des mentor\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p>La <strong>conf\u00e9rence \u00ab\u00a0Women Bridging Glass Cliff\u00a0\u00bb<\/strong>, qui s&rsquo;est tenue le 15 novembre \u00e0 l&rsquo;Universit\u00e9 de Galatasaray, Ortak\u00f6y, a constitu\u00e9 la derni\u00e8re \u00e9tape du projet et quelle derni\u00e8re \u00e9tape !<\/p>\n<p>&nbsp;<\/p>\n<p>La conf\u00e9rence a d\u00e9but\u00e9 par un discours inaugural de Melek Sine Berkem, Pr\u00e9sidente du SI Etiler, suivi par la Pr\u00e9sidente du SI Turquie, Dr. Nur Velidedeoglu Kavuncu, et la Pr\u00e9sidente du SIE Anna Wszelaczy\u0144ska, suivie par la Cheffe adjointe de la soci\u00e9t\u00e9 civile, Paolo Scialla, et enfin par A. Hakan Ati, Directrice des affaires europ\u00e9ennes au Minist\u00e8re des affaires \u00e9trang\u00e8res de Turquie. Apr\u00e8s les discours d&rsquo;ouverture, Z. G\u00fcl \u00dcst\u00fcn, chef de projet de SAGE, a pr\u00e9sent\u00e9 le fructueux projet.<\/p>\n<p>&nbsp;<\/p>\n<p>Des Soroptimist de Belgique, du Danemark, d&rsquo;Islande, d&rsquo;Isra\u00ebl, du Kenya, du Kowe\u00eft, d&rsquo;Autriche, de Pologne, du Rwanda, de Suisse et bien s\u00fbr de nombreux clubs de Turquie ont particip\u00e9 \u00e0 cette conf\u00e9rence internationale. Le programme contenait d&rsquo;excellentes conf\u00e9renci\u00e8res et des d\u00e9bats pertinents, anim\u00e9s par des Soroptimist et des non-Soroptimist. En tant que conf\u00e9renci\u00e8re principale, Ulla Madsen a \u00e9voqu\u00e9 l&rsquo;\u00e9galit\u00e9 des sexes au Danemark et, plus particuli\u00e8rement, le mod\u00e8le du cong\u00e9 parental. J\u2019ai moi-m\u00eame particip\u00e9 \u00e0 une table ronde intitul\u00e9e \u00a0\u00bb Enlightening best practices: Rwanda, Belgique, Kenya et Islande\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>J&rsquo;ai parl\u00e9 de la voie vers l&rsquo;\u00e9galit\u00e9 men\u00e9e en Islande et de la mani\u00e8re par laquelle le pays s&rsquo;est hiss\u00e9 en t\u00eate de l&rsquo;indice mondial de l&rsquo;\u00e9cart entre les sexes, pour la dixi\u00e8me ann\u00e9e cons\u00e9cutive. Quel est le secret du succ\u00e8s de l&rsquo;Islande ? Quelles sont les le\u00e7ons apprises ? En bref, l&rsquo;\u00e9galit\u00e9 entre les sexes ne se r\u00e9alise pas d&rsquo;elle-m\u00eame. Elle exige l&rsquo;action collective et la solidarit\u00e9 des femmes, d\u00e9fenseurs des droits de l\u2019homme, la volont\u00e9 politique et des outils tels que la l\u00e9gislation, un budget sensible \u00e0 la question du genre et des quotas. J&rsquo;ai parcouru la chronologie depuis 1915, ann\u00e9e o\u00f9 les femmes islandaises ont obtenu le droit de vote, l&rsquo;\u00e9galit\u00e9 des droits, l&rsquo;\u00e9galit\u00e9 de r\u00e9mun\u00e9ration, l&rsquo;alliance de femmes, la premi\u00e8re femme pr\u00e9sidente, le cong\u00e9 parental partag\u00e9, les quotas au conseil d&rsquo;administration et ceci jusqu&rsquo;en 2017, ann\u00e9e d&rsquo;entr\u00e9e en vigueur de la certification sur l&rsquo;\u00e9galit\u00e9 salariale. Pour celles qui veulent en apprendre d\u2019avantage sur la m\u00e9thode islandaise :<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/worldeconomicforum\/videos\/10154881276321479\/\">https:\/\/www.facebook.com\/worldeconomicforum\/videos\/10154881276321479\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Carolien Demey, pr\u00e9sidente \u00e9lue du SIE, a quant \u00e0 elle parl\u00e9 de l&rsquo;am\u00e9lioration de l&rsquo;\u00e9galit\u00e9 des sexes dans la vie professionnelle, o\u00f9, en tant que femmes, nous devons aider les autres femmes en les faisant passer au niveau sup\u00e9rieur. Nous devons \u00eatre conscientes que chaque niveau sup\u00e9rieur refl\u00e8te l&rsquo;\u00e9galit\u00e9 entre les sexes du niveau sous-jacent. Des quotas ont \u00e9t\u00e9 mis en place en Belgique, de sorte qu&rsquo;aujourd&rsquo;hui, dans un plus grand nombre de professions, d&rsquo;entreprises publiques, d&rsquo;universit\u00e9s et certainement en politique, davantage de femmes s&rsquo;impliquent. Avec cet exemple, les secteurs o\u00f9 il n&rsquo;y a pas de quota sont aussi en mesure de voir les avantages d&rsquo;avoir plus de femmes dans leurs conseils d&rsquo;administration&#8230; Cependant, la progression est lente et il reste encore un long chemin \u00e0 parcourir.<\/p>\n<p>&nbsp;<\/p>\n<p>Elizabeth Nyadwe, conseill\u00e8re sp\u00e9cial Lobbying du SIE, a \u00e9voqu\u00e9 la nouvelle constitution \u00a0promulgu\u00e9e par le Kenya en 2010. Cette derni\u00e8re approuve la repr\u00e9sentation proportionnelle dans le syst\u00e8me \u00e9lectoral. Les femmes et les populations vuln\u00e9rables sont d\u00e9sormais prises en compte dans le syst\u00e8me politique, ce qui a encourag\u00e9 les femmes \u00e0 s\u2019investir davantage dans des postes \u00e0 responsabilit\u00e9 \u00e0 travers le pays. Les petits pas dans l&rsquo;ar\u00e8ne politique ont fait des \u00e9tincelles et d\u00e9clench\u00e9 une sensibilit\u00e9 accrue \u00e0 la question du genre sur le lieu de travail. La nouvelle constitution kenyane a donc eu un impact tr\u00e8s positif pour le d\u00e9bat sur le genre.<\/p>\n<p>&nbsp;<\/p>\n<p>Appoline Kangabire, Gouverneure du Rwanda, s&rsquo;est pench\u00e9e sur la vie des femmes dans son pays et sur les raisons pour lesquelles, apr\u00e8s le g\u00e9nocide de 1994, le Rwanda a maintenu son engagement concernant l&rsquo;autonomisation politique des femmes. Il demeure en effet le pays connaissant la plus forte proportion de femmes parlementaires au monde (61%) et presque la parit\u00e9 dans les postes minist\u00e9riels. Le Rwanda occupe la 6e place de l&rsquo;Indice mondial de l&rsquo;\u00e9cart entre les sexes.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-16080\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1.jpg\" alt=\"\" width=\"889\" height=\"243\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1.jpg 2470w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-300x82.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-1024x279.jpg 1024w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-768x209.jpg 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-1536x419.jpg 1536w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-2048x558.jpg 2048w\" sizes=\"(max-width: 889px) 100vw, 889px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La conf\u00e9rence s&rsquo;est termin\u00e9e par un d\u00e9bat, men\u00e9 par des femmes turques non-Soroptimist, qui a mis en lumi\u00e8re le th\u00e8me \u00ab\u00a0Bridging to Glass Cliff \u00ab\u00a0. Les Soroptimist du SI Club Etiler sont extr\u00eamement actives et efficaces et peuvent \u00eatre tr\u00e8s fi\u00e8res de leur projet et de ses succ\u00e8s.<\/p>\n<p>&nbsp;<\/p>\n<p>Parall\u00e8lement \u00e0 la conf\u00e9rence, nous avons b\u00e9n\u00e9fici\u00e9 d&rsquo;un g\u00e9n\u00e9reux programme de d\u00e9couvertes et de visites: une promenade sur les rives du Bosphore, une balade dans la vieille ville du c\u00f4t\u00e9 asiatique et une visite guid\u00e9e de la vieille Istanbul, o\u00f9 nous n&rsquo;avons pas \u00e9t\u00e9 bombard\u00e9es de noms et de dates mais o\u00f9 nous avons appris comment vivre l&rsquo;histoire d&rsquo;Istanbul et le r\u00e8gne ottoman.\u00a0La cuisine turque est c\u00e9l\u00e8bre et nous avons pu l&rsquo;exp\u00e9rimenter au petit-d\u00e9jeuner, au d\u00e9jeuner et au d\u00eener ! Dans la splendide maison d&rsquo;Emine, nous avons toutes \u00e9t\u00e9 invit\u00e9es \u00e0 un d\u00eener sp\u00e9cial, ainsi qu&rsquo;\u00e0 un repas de gala au Mus\u00e9e naval de Besiktas et \u00e0 un d\u00eener d&rsquo;amiti\u00e9, dans un tr\u00e8s bon restaurant du c\u00f4t\u00e9 asiatique du Bosphore, o\u00f9 il y a eu un \u00e9change international tr\u00e8s vivant.<\/p>\n<p>&nbsp;<\/p>\n<p>Bien que le s\u00e9jour dans la m\u00e9tropole d&rsquo;Istanbul ait \u00e9t\u00e9 bref, j&rsquo;ai v\u00e9cu tant de nouvelles sensations et exp\u00e9riences. Je me suis \u00e9galement r\u00e9jouie de la compagnie des Soroptimist de Turquie et du monde entier.\u00a0Aujourd&rsquo;hui, deux semaines plus tard et de retour chez moi, je revis l&rsquo;atmosph\u00e8re d&rsquo;Istanbul et la grande hospitalit\u00e9 de nos s\u0153urs Soroptimist, qui auront toujours une place sp\u00e9ciale dans mon c\u0153ur.<\/p>\n<div class=\"image-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-2.jpg\" alt=\"Schema 2\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il est midi et je suis \u00e0 l&rsquo;a\u00e9roport de Copenhague\u00a0; je viens d&rsquo;arriver avec un vol d&rsquo;Islande. J&rsquo;attends qu&rsquo;Ulla Madsen, ancienne pr\u00e9sidente du SIE et directrice adjointe du Lobbying du [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":37239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[106,109],"tags":[172],"class_list":["post-16154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-advocacy","tag-advocacy"],"acf":{"article_photo_de_couverture":false,"article_chapeau":"","article_contenu":[{"article_titre_du_paragraphe":"","article_paragraphe":"<p>Il est midi et je suis \u00e0 l&rsquo;a\u00e9roport de Copenhague\u00a0; je viens d&rsquo;arriver avec un vol d&rsquo;Islande. J&rsquo;attends qu&rsquo;Ulla Madsen, ancienne pr\u00e9sidente du SIE et directrice adjointe du Lobbying du SI, se joigne \u00e0 moi pour que nous nous rendions ensemble \u00e0 Istanbul afin de participer \u00e0 une <strong>conf\u00e9rence internationale sur l&rsquo;\u00e9galit\u00e9 des sexes dans la vie professionnelle<\/strong>, organis\u00e9e par <strong>SI Club Etiler<\/strong>. Nous sommes accueillies \u00e0 l&rsquo;a\u00e9roport d&rsquo;Istanbul par la pr\u00e9sidente fondatrice du Club, Emine Erdem, secr\u00e9taire et chauffeur, qui nous emm\u00e8ne dans sa belle maison, o\u00f9 nous profiterons d&rsquo;un accueil tout particulier pendant notre s\u00e9jour \u00e0 Istanbul.<\/p>\n<p>&nbsp;<\/p>\n<p>Cr\u00e9\u00e9 en 1988, le <strong>SI Club Etiler<\/strong> c\u00e9l\u00e8bre son <strong>30\u00e8me anniversaire<\/strong> sous le th\u00e8me \u00ab\u00a0Soroptimists Advocate Gender Equality (SAGE)\u00a0\u00bb. Il a sollicit\u00e9 et re\u00e7u une subvention pour le projet \u00ab\u00a0Grant Scheme for Grassroots Civil Society Organizations\u00a0\u00bb, qui est cofinanc\u00e9 par l&rsquo;Union europ\u00e9enne (UE) et la R\u00e9publique de Turquie.<\/p>\n<p>&nbsp;<\/p>\n<p>Le projet se subdivise en quatre parties:<\/p>\n<ul>\n<li>Les activit\u00e9s \u00ab\u00a0ChangEquality\u00a0\u00bb visant \u00e0 sensibiliser les \u00e9tudiants \u00e0 l&rsquo;\u00e9galit\u00e9 entre les sexes dans la vie professionnelle\u00a0;<\/li>\n<li>Les ambassadeurs du programme \u00ab\u00a0ChangEquality\u00a0\u00bb pour assurer la p\u00e9rennit\u00e9 du projet\u00a0;<\/li>\n<li>\u00ab\u00a0SAGE\u00a0\u00bb dans un programme de mentorat dans le milieu du travail, qui vise \u00e0 \u00e9quiper et \u00e0 autonomiser les femmes face aux obstacles qu&rsquo;elles rencontreront dans leur vie professionnelle\u00a0;<\/li>\n<li>\u00ab\u00a0Women Bridging Glass Cliff\u00a0\u00bb, conf\u00e9rence internationale sur l&rsquo;\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>En janvier 2019, le Club Etiler a contact\u00e9 les rectorats et des associations d&rsquo;\u00e9tudiants de diverses universit\u00e9s d&rsquo;Istanbul. Au lieu de faire des pr\u00e9sentations de sensibilisation, ses membres ont organis\u00e9 un jeu: \u00ab\u00a0ChangEquality\u00a0\u00bb, jou\u00e9 par 8 \u00e0 28 personnes. Ces derni\u00e8res sont invit\u00e9es \u00e0 r\u00e9pondre \u00e0 des questions et \u00e0 analyser des cas en groupes, ainsi qu\u2019\u00e0 formuler de nouvelles perspectives qui leur permettront ensuite de comprendre la situation actuelle, de discuter des in\u00e9galit\u00e9s, de repenser les probl\u00e8mes et proposer des solutions. Cela a d\u00e9j\u00e0 touch\u00e9 350 \u00e9tudiants.<\/p>\n<p>&nbsp;<\/p>\n<p>Pour donner suite aux r\u00e9sultats du jeu \u00ab\u00a0ChangEqualty\u00a0\u00bb, un programme a \u00e9t\u00e9 \u00e9labor\u00e9 dans le cadre duquel soixante personnes ont suivi une formation. Dix d&rsquo;entre elles ont \u00e9t\u00e9 nomm\u00e9es ambassadeurs \u00ab\u00a0ChangEquality\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>La troisi\u00e8me \u00e9tape a consist\u00e9 en une formation de mentorat de deux jours, en avril dernier, \u00e0 laquelle ont particip\u00e9 vingt-sept candidats mentors de huit clubs d&rsquo;Istanbul. Ensuite, une formation pour les personnes mentor\u00e9es a \u00e9t\u00e9 organis\u00e9e avec vingt-huit \u00e9tudiants. Vingt-cinq mentors et vingt-cinq mentor\u00e9s ont \u00e9t\u00e9 choisis pour six \u00e0 huit entrevues, pendant sept mois. Le programme a pour but de permettre aux mentors et aux mentor\u00e9s d&rsquo;acqu\u00e9rir des comp\u00e9tences; les personnes mentor\u00e9es acqui\u00e8rent ainsi les aptitudes n\u00e9cessaires pour faire face aux d\u00e9fis, auxquels ils peuvent \u00eatre confront\u00e9s dans leur vie professionnelle, tandis que les mentors apprennent \u00e0 renforcer leur capacit\u00e9 \u00e0 g\u00e9rer des processus structur\u00e9s, qui contribueront ensuite \u00e0 la valorisation des mentor\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p>La <strong>conf\u00e9rence \u00ab\u00a0Women Bridging Glass Cliff\u00a0\u00bb<\/strong>, qui s&rsquo;est tenue le 15 novembre \u00e0 l&rsquo;Universit\u00e9 de Galatasaray, Ortak\u00f6y, a constitu\u00e9 la derni\u00e8re \u00e9tape du projet et quelle derni\u00e8re \u00e9tape !<\/p>\n<p>&nbsp;<\/p>\n<p>La conf\u00e9rence a d\u00e9but\u00e9 par un discours inaugural de Melek Sine Berkem, Pr\u00e9sidente du SI Etiler, suivi par la Pr\u00e9sidente du SI Turquie, Dr. Nur Velidedeoglu Kavuncu, et la Pr\u00e9sidente du SIE Anna Wszelaczy\u0144ska, suivie par la Cheffe adjointe de la soci\u00e9t\u00e9 civile, Paolo Scialla, et enfin par A. Hakan Ati, Directrice des affaires europ\u00e9ennes au Minist\u00e8re des affaires \u00e9trang\u00e8res de Turquie. Apr\u00e8s les discours d&rsquo;ouverture, Z. G\u00fcl \u00dcst\u00fcn, chef de projet de SAGE, a pr\u00e9sent\u00e9 le fructueux projet.<\/p>\n<p>&nbsp;<\/p>\n<p>Des Soroptimist de Belgique, du Danemark, d&rsquo;Islande, d&rsquo;Isra\u00ebl, du Kenya, du Kowe\u00eft, d&rsquo;Autriche, de Pologne, du Rwanda, de Suisse et bien s\u00fbr de nombreux clubs de Turquie ont particip\u00e9 \u00e0 cette conf\u00e9rence internationale. Le programme contenait d&rsquo;excellentes conf\u00e9renci\u00e8res et des d\u00e9bats pertinents, anim\u00e9s par des Soroptimist et des non-Soroptimist. En tant que conf\u00e9renci\u00e8re principale, Ulla Madsen a \u00e9voqu\u00e9 l&rsquo;\u00e9galit\u00e9 des sexes au Danemark et, plus particuli\u00e8rement, le mod\u00e8le du cong\u00e9 parental. J\u2019ai moi-m\u00eame particip\u00e9 \u00e0 une table ronde intitul\u00e9e \u00a0\u00bb Enlightening best practices: Rwanda, Belgique, Kenya et Islande\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>J&rsquo;ai parl\u00e9 de la voie vers l&rsquo;\u00e9galit\u00e9 men\u00e9e en Islande et de la mani\u00e8re par laquelle le pays s&rsquo;est hiss\u00e9 en t\u00eate de l&rsquo;indice mondial de l&rsquo;\u00e9cart entre les sexes, pour la dixi\u00e8me ann\u00e9e cons\u00e9cutive. Quel est le secret du succ\u00e8s de l&rsquo;Islande ? Quelles sont les le\u00e7ons apprises ? En bref, l&rsquo;\u00e9galit\u00e9 entre les sexes ne se r\u00e9alise pas d&rsquo;elle-m\u00eame. Elle exige l&rsquo;action collective et la solidarit\u00e9 des femmes, d\u00e9fenseurs des droits de l\u2019homme, la volont\u00e9 politique et des outils tels que la l\u00e9gislation, un budget sensible \u00e0 la question du genre et des quotas. J&rsquo;ai parcouru la chronologie depuis 1915, ann\u00e9e o\u00f9 les femmes islandaises ont obtenu le droit de vote, l&rsquo;\u00e9galit\u00e9 des droits, l&rsquo;\u00e9galit\u00e9 de r\u00e9mun\u00e9ration, l&rsquo;alliance de femmes, la premi\u00e8re femme pr\u00e9sidente, le cong\u00e9 parental partag\u00e9, les quotas au conseil d&rsquo;administration et ceci jusqu&rsquo;en 2017, ann\u00e9e d&rsquo;entr\u00e9e en vigueur de la certification sur l&rsquo;\u00e9galit\u00e9 salariale. Pour celles qui veulent en apprendre d\u2019avantage sur la m\u00e9thode islandaise :<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/worldeconomicforum\/videos\/10154881276321479\/\">https:\/\/www.facebook.com\/worldeconomicforum\/videos\/10154881276321479\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Carolien Demey, pr\u00e9sidente \u00e9lue du SIE, a quant \u00e0 elle parl\u00e9 de l&rsquo;am\u00e9lioration de l&rsquo;\u00e9galit\u00e9 des sexes dans la vie professionnelle, o\u00f9, en tant que femmes, nous devons aider les autres femmes en les faisant passer au niveau sup\u00e9rieur. Nous devons \u00eatre conscientes que chaque niveau sup\u00e9rieur refl\u00e8te l&rsquo;\u00e9galit\u00e9 entre les sexes du niveau sous-jacent. Des quotas ont \u00e9t\u00e9 mis en place en Belgique, de sorte qu&rsquo;aujourd&rsquo;hui, dans un plus grand nombre de professions, d&rsquo;entreprises publiques, d&rsquo;universit\u00e9s et certainement en politique, davantage de femmes s&rsquo;impliquent. Avec cet exemple, les secteurs o\u00f9 il n&rsquo;y a pas de quota sont aussi en mesure de voir les avantages d&rsquo;avoir plus de femmes dans leurs conseils d&rsquo;administration&#8230; Cependant, la progression est lente et il reste encore un long chemin \u00e0 parcourir.<\/p>\n<p>&nbsp;<\/p>\n<p>Elizabeth Nyadwe, conseill\u00e8re sp\u00e9cial Lobbying du SIE, a \u00e9voqu\u00e9 la nouvelle constitution \u00a0promulgu\u00e9e par le Kenya en 2010. Cette derni\u00e8re approuve la repr\u00e9sentation proportionnelle dans le syst\u00e8me \u00e9lectoral. Les femmes et les populations vuln\u00e9rables sont d\u00e9sormais prises en compte dans le syst\u00e8me politique, ce qui a encourag\u00e9 les femmes \u00e0 s\u2019investir davantage dans des postes \u00e0 responsabilit\u00e9 \u00e0 travers le pays. Les petits pas dans l&rsquo;ar\u00e8ne politique ont fait des \u00e9tincelles et d\u00e9clench\u00e9 une sensibilit\u00e9 accrue \u00e0 la question du genre sur le lieu de travail. La nouvelle constitution kenyane a donc eu un impact tr\u00e8s positif pour le d\u00e9bat sur le genre.<\/p>\n<p>&nbsp;<\/p>\n<p>Appoline Kangabire, Gouverneure du Rwanda, s&rsquo;est pench\u00e9e sur la vie des femmes dans son pays et sur les raisons pour lesquelles, apr\u00e8s le g\u00e9nocide de 1994, le Rwanda a maintenu son engagement concernant l&rsquo;autonomisation politique des femmes. Il demeure en effet le pays connaissant la plus forte proportion de femmes parlementaires au monde (61%) et presque la parit\u00e9 dans les postes minist\u00e9riels. Le Rwanda occupe la 6e place de l&rsquo;Indice mondial de l&rsquo;\u00e9cart entre les sexes.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-16080\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-300x82.jpg\" alt=\"\" width=\"889\" height=\"243\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-300x82.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-1024x279.jpg 1024w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-768x209.jpg 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-1536x419.jpg 1536w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-1-2048x558.jpg 2048w\" sizes=\"(max-width: 889px) 100vw, 889px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La conf\u00e9rence s&rsquo;est termin\u00e9e par un d\u00e9bat, men\u00e9 par des femmes turques non-Soroptimist, qui a mis en lumi\u00e8re le th\u00e8me \u00ab\u00a0Bridging to Glass Cliff \u00ab\u00a0. Les Soroptimist du SI Club Etiler sont extr\u00eamement actives et efficaces et peuvent \u00eatre tr\u00e8s fi\u00e8res de leur projet et de ses succ\u00e8s.<\/p>\n<p>&nbsp;<\/p>\n<p>Parall\u00e8lement \u00e0 la conf\u00e9rence, nous avons b\u00e9n\u00e9fici\u00e9 d&rsquo;un g\u00e9n\u00e9reux programme de d\u00e9couvertes et de visites: une promenade sur les rives du Bosphore, une balade dans la vieille ville du c\u00f4t\u00e9 asiatique et une visite guid\u00e9e de la vieille Istanbul, o\u00f9 nous n&rsquo;avons pas \u00e9t\u00e9 bombard\u00e9es de noms et de dates mais o\u00f9 nous avons appris comment vivre l&rsquo;histoire d&rsquo;Istanbul et le r\u00e8gne ottoman.\u00a0La cuisine turque est c\u00e9l\u00e8bre et nous avons pu l&rsquo;exp\u00e9rimenter au petit-d\u00e9jeuner, au d\u00e9jeuner et au d\u00eener ! Dans la splendide maison d&rsquo;Emine, nous avons toutes \u00e9t\u00e9 invit\u00e9es \u00e0 un d\u00eener sp\u00e9cial, ainsi qu&rsquo;\u00e0 un repas de gala au Mus\u00e9e naval de Besiktas et \u00e0 un d\u00eener d&rsquo;amiti\u00e9, dans un tr\u00e8s bon restaurant du c\u00f4t\u00e9 asiatique du Bosphore, o\u00f9 il y a eu un \u00e9change international tr\u00e8s vivant.<\/p>\n<p>&nbsp;<\/p>\n<p>Bien que le s\u00e9jour dans la m\u00e9tropole d&rsquo;Istanbul ait \u00e9t\u00e9 bref, j&rsquo;ai v\u00e9cu tant de nouvelles sensations et exp\u00e9riences. Je me suis \u00e9galement r\u00e9jouie de la compagnie des Soroptimist de Turquie et du monde entier.\u00a0Aujourd&rsquo;hui, deux semaines plus tard et de retour chez moi, je revis l&rsquo;atmosph\u00e8re d&rsquo;Istanbul et la grande hospitalit\u00e9 de nos s\u0153urs Soroptimist, qui auront toujours une place sp\u00e9ciale dans mon c\u0153ur.<\/p>\n","article_media_image":{"ID":16078,"id":16078,"title":"Schema 2","filename":"schema-2.jpg","filesize":37413,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-2.jpg","link":"https:\/\/www.soroptimisteurope.org\/fr\/schema-2-2\/","alt":"","author":"3","description":"","caption":"","name":"schema-2-2","status":"inherit","uploaded_to":0,"date":"2019-12-17 13:41:20","modified":"2019-12-18 12:25:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.soroptimisteurope.org\/wp-content\/plugins\/media-library-assistant\/images\/crystal\/image.png","width":480,"height":360,"sizes":{"thumbnail":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-2-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-2.jpg","medium_large-width":480,"medium_large-height":360,"large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-2.jpg","large-width":480,"large-height":360,"1536x1536":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-2.jpg","1536x1536-width":480,"1536x1536-height":360,"2048x2048":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2019\/12\/schema-2.jpg","2048x2048-width":480,"2048x2048-height":360}},"article_media_video":""}],"article_trombinoscope":false,"article_video":"","article_evenements_sociaux":false,"article_auteur_texte":"<p>Hafd\u00eds Karlsd\u00f3ttir, Secr\u00e9taire G\u00e9n\u00e9rale du SIE<\/p>\n","article_nom_contact":"","article_email_contact":"","article_numero_contact":"","article_documents":false,"article_actualites_liees":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00ab Women Bridging Glass Cliff \u00bb - Conf\u00e9rence sur l&#039;\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle - Soroptimist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab Women Bridging Glass Cliff \u00bb - Conf\u00e9rence sur l&#039;\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle - Soroptimist\" \/>\n<meta property=\"og:description\" content=\"Il est midi et je suis \u00e0 l&rsquo;a\u00e9roport de Copenhague\u00a0; je viens d&rsquo;arriver avec un vol d&rsquo;Islande. J&rsquo;attends qu&rsquo;Ulla Madsen, ancienne pr\u00e9sidente du SIE et directrice adjointe du Lobbying du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/\" \/>\n<meta property=\"og:site_name\" content=\"Soroptimist\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-19T09:00:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T09:17:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/20191116-171659-cropped-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Virginie Racine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Virginie Racine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/\"},\"author\":{\"name\":\"Virginie Racine\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"headline\":\"\u00ab Women Bridging Glass Cliff \u00bb &#8211; Conf\u00e9rence sur l&rsquo;\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle\",\"datePublished\":\"2019-12-19T09:00:38+00:00\",\"dateModified\":\"2025-05-13T09:17:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/\"},\"wordCount\":1602,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20191116-171659-cropped-scaled.jpg\",\"keywords\":[\"Advocacy\"],\"articleSection\":[\"News\",\"Advocacy\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/\",\"name\":\"\u00ab Women Bridging Glass Cliff \u00bb - Conf\u00e9rence sur l'\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle - Soroptimist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20191116-171659-cropped-scaled.jpg\",\"datePublished\":\"2019-12-19T09:00:38+00:00\",\"dateModified\":\"2025-05-13T09:17:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20191116-171659-cropped-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/20191116-171659-cropped-scaled.jpg\",\"width\":2560,\"height\":1315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab Women Bridging Glass Cliff \u00bb &#8211; Conf\u00e9rence sur l&#8217;\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/\",\"name\":\"Soroptimist\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\",\"name\":\"Virginie Racine\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/author\\\/adminsorop2k21\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab Women Bridging Glass Cliff \u00bb - Conf\u00e9rence sur l'\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle - Soroptimist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00ab Women Bridging Glass Cliff \u00bb - Conf\u00e9rence sur l'\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle - Soroptimist","og_description":"Il est midi et je suis \u00e0 l&rsquo;a\u00e9roport de Copenhague\u00a0; je viens d&rsquo;arriver avec un vol d&rsquo;Islande. J&rsquo;attends qu&rsquo;Ulla Madsen, ancienne pr\u00e9sidente du SIE et directrice adjointe du Lobbying du [&hellip;]","og_url":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/","og_site_name":"Soroptimist","article_published_time":"2019-12-19T09:00:38+00:00","article_modified_time":"2025-05-13T09:17:11+00:00","og_image":[{"width":2560,"height":1315,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/20191116-171659-cropped-scaled.jpg","type":"image\/jpeg"}],"author":"Virginie Racine","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Virginie Racine","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/#article","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/"},"author":{"name":"Virginie Racine","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"headline":"\u00ab Women Bridging Glass Cliff \u00bb &#8211; Conf\u00e9rence sur l&rsquo;\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle","datePublished":"2019-12-19T09:00:38+00:00","dateModified":"2025-05-13T09:17:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/"},"wordCount":1602,"commentCount":0,"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/20191116-171659-cropped-scaled.jpg","keywords":["Advocacy"],"articleSection":["News","Advocacy"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/","url":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/","name":"\u00ab Women Bridging Glass Cliff \u00bb - Conf\u00e9rence sur l'\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle - Soroptimist","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/#primaryimage"},"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/20191116-171659-cropped-scaled.jpg","datePublished":"2019-12-19T09:00:38+00:00","dateModified":"2025-05-13T09:17:11+00:00","author":{"@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"breadcrumb":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/#primaryimage","url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/20191116-171659-cropped-scaled.jpg","contentUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/20191116-171659-cropped-scaled.jpg","width":2560,"height":1315},{"@type":"BreadcrumbList","@id":"https:\/\/www.soroptimisteurope.org\/fr\/women-bridging-glass-cliff-conference-sur-legalite-entre-les-femmes-et-les-hommes-dans-la-vie-professionnelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soroptimisteurope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab Women Bridging Glass Cliff \u00bb &#8211; Conf\u00e9rence sur l&#8217;\u00e9galit\u00e9 entre les femmes et les hommes dans la vie professionnelle"}]},{"@type":"WebSite","@id":"https:\/\/www.soroptimisteurope.org\/#website","url":"https:\/\/www.soroptimisteurope.org\/","name":"Soroptimist","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soroptimisteurope.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619","name":"Virginie Racine","url":"https:\/\/www.soroptimisteurope.org\/fr\/author\/adminsorop2k21\/"}]}},"_links":{"self":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/16154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/comments?post=16154"}],"version-history":[{"count":0,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/16154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media\/37239"}],"wp:attachment":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media?parent=16154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/categories?post=16154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/tags?post=16154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}