{"id":19185,"date":"2020-11-29T23:26:19","date_gmt":"2020-11-29T22:26:19","guid":{"rendered":"http:\/\/www.soroptimisteurope.org\/?p=19185"},"modified":"2025-05-13T11:17:36","modified_gmt":"2025-05-13T09:17:36","slug":"campagne-oranger-le-monde-2020-si-suede","status":"publish","type":"post","link":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/","title":{"rendered":"Campagne \u00ab\u00a0Oranger le monde\u00a0\u00bb 2020 &#8211; SI Su\u00e8de"},"content":{"rendered":"<h3>Soroptimist Union de Su\u00e8de<\/h3>\n<p>Comme chaque ann\u00e9e, l\u2019Union de Su\u00e8de se mobilise pour la campagne \u00ab\u00a0Oranger le monde\u00a0\u00bb. La crise sanitaire demande toutefois plus de flexibilit\u00e9 et d\u2019inventivit\u00e9. C\u2019est pourquoi l\u2019Union offrira trois conf\u00e9rences en ligne les 26, 30 novembre et 8 d\u00e9cembre pour ses membres et pour tout public int\u00e9ress\u00e9, afin de mobiliser et d\u2019alerter le plus grand nombre sur la th\u00e9matique de la violence faite aux femmes et aux filles.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-19178\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden.jpg\" alt=\"\" width=\"696\" height=\"517\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden.jpg 899w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-300x223.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-768x570.jpg 768w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Pendant ces 16 jours d\u2019activisme, les clubs soroptimist su\u00e9dois ne seront pas en reste et proposeront des actions diverses et vari\u00e9es \u00e0 travers tout le pays. Pour n\u2019en citer que quelques-unes, le club de Gothenburg, en partenariat avec Zonta International et UN Women, d\u00e9livrera des discours et des conf\u00e9rences publiques, distribuera des brochures informatives et vendra des pampilles oranges lumineuses. Les clubs d\u2019\u00d6rebro-Wadk\u00f6ping, Landskrona et Falun organiseront quant \u00e0 eux des marches et des manifestations color\u00e9es de parapluies oranges, pendant que le club de Soten\u00e4s se lancera dans la confection de confitures et de vestes oranges\u00a0! Finalement, la tour d\u2019eau d\u2019Ystad se parera d\u2019orange, tout comme de nombreux b\u00e2timents publics \u00e0 travers le pays.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019argent r\u00e9colt\u00e9 par l\u2019Union lors de cette campagne servira \u00e0 soutenir son projet RE-START, qui aide les femmes et les jeunes filles en foyer.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-19180\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-conference.jpg\" alt=\"\" width=\"610\" height=\"888\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-conference.jpg 613w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-conference-206x300.jpg 206w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soroptimist Union de Su\u00e8de Comme chaque ann\u00e9e, l\u2019Union de Su\u00e8de se mobilise pour la campagne \u00ab\u00a0Oranger le monde\u00a0\u00bb. La crise sanitaire demande toutefois plus de flexibilit\u00e9 et d\u2019inventivit\u00e9. C\u2019est pourquoi [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":37606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[127,129],"tags":[188],"class_list":["post-19185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eradiquer-la-violence-a-legard-des-femmes","category-nouvelles","tag-eradiquer-la-violence-a-legard-des-femmes"],"acf":{"article_photo_de_couverture":false,"article_chapeau":"","article_contenu":[{"article_titre_du_paragraphe":"Soroptimist Union de Su\u00e8de","article_paragraphe":"<p>Comme chaque ann\u00e9e, l\u2019Union de Su\u00e8de se mobilise pour la campagne \u00ab\u00a0Oranger le monde\u00a0\u00bb. La crise sanitaire demande toutefois plus de flexibilit\u00e9 et d\u2019inventivit\u00e9. C\u2019est pourquoi l\u2019Union offrira trois conf\u00e9rences en ligne les 26, 30 novembre et 8 d\u00e9cembre pour ses membres et pour tout public int\u00e9ress\u00e9, afin de mobiliser et d\u2019alerter le plus grand nombre sur la th\u00e9matique de la violence faite aux femmes et aux filles.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-19178\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-300x223.jpg\" alt=\"\" width=\"696\" height=\"517\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-300x223.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-768x570.jpg 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden.jpg 899w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Pendant ces 16 jours d\u2019activisme, les clubs soroptimist su\u00e9dois ne seront pas en reste et proposeront des actions diverses et vari\u00e9es \u00e0 travers tout le pays. Pour n\u2019en citer que quelques-unes, le club de Gothenburg, en partenariat avec Zonta International et UN Women, d\u00e9livrera des discours et des conf\u00e9rences publiques, distribuera des brochures informatives et vendra des pampilles oranges lumineuses. Les clubs d\u2019\u00d6rebro-Wadk\u00f6ping, Landskrona et Falun organiseront quant \u00e0 eux des marches et des manifestations color\u00e9es de parapluies oranges, pendant que le club de Soten\u00e4s se lancera dans la confection de confitures et de vestes oranges\u00a0! Finalement, la tour d\u2019eau d\u2019Ystad se parera d\u2019orange, tout comme de nombreux b\u00e2timents publics \u00e0 travers le pays.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019argent r\u00e9colt\u00e9 par l\u2019Union lors de cette campagne servira \u00e0 soutenir son projet RE-START, qui aide les femmes et les jeunes filles en foyer.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19180\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-conference-206x300.jpg\" alt=\"\" width=\"610\" height=\"888\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-conference-206x300.jpg 206w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/si-sweden-conference.jpg 613w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/><\/p>\n","article_media_image":false,"article_media_video":""}],"article_trombinoscope":false,"article_video":"","article_evenements_sociaux":false,"article_auteur_texte":"<p>Par l&rsquo;\u00e9quipe du Programme du SIE<\/p>\n","article_nom_contact":"","article_email_contact":"","article_numero_contact":"","article_documents":false,"article_actualites_liees":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campagne &quot;Oranger le monde&quot; 2020 - SI Su\u00e8de - Soroptimist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campagne &quot;Oranger le monde&quot; 2020 - SI Su\u00e8de - Soroptimist\" \/>\n<meta property=\"og:description\" content=\"Soroptimist Union de Su\u00e8de Comme chaque ann\u00e9e, l\u2019Union de Su\u00e8de se mobilise pour la campagne \u00ab\u00a0Oranger le monde\u00a0\u00bb. La crise sanitaire demande toutefois plus de flexibilit\u00e9 et d\u2019inventivit\u00e9. C\u2019est pourquoi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/\" \/>\n<meta property=\"og:site_name\" content=\"Soroptimist\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-29T22:26:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T09:17:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/otw-poster-2020-horizontal-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Virginie Racine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Virginie Racine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/\"},\"author\":{\"name\":\"Virginie Racine\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"headline\":\"Campagne \u00ab\u00a0Oranger le monde\u00a0\u00bb 2020 &#8211; SI Su\u00e8de\",\"datePublished\":\"2020-11-29T22:26:19+00:00\",\"dateModified\":\"2025-05-13T09:17:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/\"},\"wordCount\":242,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/otw-poster-2020-horizontal-3.png\",\"keywords\":[\"Eradiquer la violence \u00e0 l'\u00e9gard des femmes\"],\"articleSection\":[\"Eradiquer la violence \u00e0 l&#039;\u00e9gard des femmes\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/\",\"name\":\"Campagne \\\"Oranger le monde\\\" 2020 - SI Su\u00e8de - Soroptimist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/otw-poster-2020-horizontal-3.png\",\"datePublished\":\"2020-11-29T22:26:19+00:00\",\"dateModified\":\"2025-05-13T09:17:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/otw-poster-2020-horizontal-3.png\",\"contentUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/otw-poster-2020-horizontal-3.png\",\"width\":820,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/campagne-oranger-le-monde-2020-si-suede\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne &#8220;Oranger le monde&#8221; 2020 &#8211; SI Su\u00e8de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/\",\"name\":\"Soroptimist\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\",\"name\":\"Virginie Racine\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/author\\\/adminsorop2k21\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campagne \"Oranger le monde\" 2020 - SI Su\u00e8de - Soroptimist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/","og_locale":"fr_FR","og_type":"article","og_title":"Campagne \"Oranger le monde\" 2020 - SI Su\u00e8de - Soroptimist","og_description":"Soroptimist Union de Su\u00e8de Comme chaque ann\u00e9e, l\u2019Union de Su\u00e8de se mobilise pour la campagne \u00ab\u00a0Oranger le monde\u00a0\u00bb. La crise sanitaire demande toutefois plus de flexibilit\u00e9 et d\u2019inventivit\u00e9. C\u2019est pourquoi [&hellip;]","og_url":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/","og_site_name":"Soroptimist","article_published_time":"2020-11-29T22:26:19+00:00","article_modified_time":"2025-05-13T09:17:36+00:00","og_image":[{"width":820,"height":360,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/otw-poster-2020-horizontal-3.png","type":"image\/png"}],"author":"Virginie Racine","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Virginie Racine","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/#article","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/"},"author":{"name":"Virginie Racine","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"headline":"Campagne \u00ab\u00a0Oranger le monde\u00a0\u00bb 2020 &#8211; SI Su\u00e8de","datePublished":"2020-11-29T22:26:19+00:00","dateModified":"2025-05-13T09:17:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/"},"wordCount":242,"commentCount":0,"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/otw-poster-2020-horizontal-3.png","keywords":["Eradiquer la violence \u00e0 l'\u00e9gard des femmes"],"articleSection":["Eradiquer la violence \u00e0 l&#039;\u00e9gard des femmes","Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/","url":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/","name":"Campagne \"Oranger le monde\" 2020 - SI Su\u00e8de - Soroptimist","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/#primaryimage"},"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/otw-poster-2020-horizontal-3.png","datePublished":"2020-11-29T22:26:19+00:00","dateModified":"2025-05-13T09:17:36+00:00","author":{"@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"breadcrumb":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/#primaryimage","url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/otw-poster-2020-horizontal-3.png","contentUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/otw-poster-2020-horizontal-3.png","width":820,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.soroptimisteurope.org\/fr\/campagne-oranger-le-monde-2020-si-suede\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soroptimisteurope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Campagne &#8220;Oranger le monde&#8221; 2020 &#8211; SI Su\u00e8de"}]},{"@type":"WebSite","@id":"https:\/\/www.soroptimisteurope.org\/#website","url":"https:\/\/www.soroptimisteurope.org\/","name":"Soroptimist","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soroptimisteurope.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619","name":"Virginie Racine","url":"https:\/\/www.soroptimisteurope.org\/fr\/author\/adminsorop2k21\/"}]}},"_links":{"self":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/19185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/comments?post=19185"}],"version-history":[{"count":0,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/19185\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media\/37606"}],"wp:attachment":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media?parent=19185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/categories?post=19185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/tags?post=19185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}