{"id":19235,"date":"2020-12-04T07:20:22","date_gmt":"2020-12-04T06:20:22","guid":{"rendered":"http:\/\/www.soroptimisteurope.org\/?p=19235"},"modified":"2025-05-13T11:17:37","modified_gmt":"2025-05-13T09:17:37","slug":"societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees","status":"publish","type":"post","link":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/","title":{"rendered":"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es"},"content":{"rendered":"<h3>Soroptimist Club de Volos Thetis, Gr\u00e8ce<\/h3>\n<p>Dans le cadre de la campagne \u00ab Oranger le monde \u00bb, les Soroptimist de Volos Thetis en Gr\u00e8ce ont initi\u00e9 5 actions cons\u00e9cutives afin de sensibiliser la population sur les violences faites aux femmes et les diff\u00e9rentes formes de soutien qui peuvent \u00eatre apport\u00e9es :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>1\u00e8re action<\/strong> : Projection publique du film <em>\u00ab\u00a0Zenaida\u00a0\u00bb<\/em> \u00e0 l&rsquo;Universit\u00e9 de Thessalie, suivie d&rsquo;une discussion avec les \u00e9tudiants et le r\u00e9alisateur du film sur la question de la traite. Le lendemain, un atelier sur le tournage de films traitant de la violence a \u00e9t\u00e9 donn\u00e9 en pr\u00e9sence de nombreux \u00e9tudiants.<\/li>\n<\/ul>\n<table>\n<tbody>\n<tr>\n<td width=\"200\"><\/td>\n<td width=\"200\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-19219\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-1.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-1.jpg 678w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-1-212x300.jpg 212w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/td>\n<td width=\"200\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul>\n<li><strong>2\u00e8me action<\/strong> : <em>\u00ab\u00a0Marche pour la libert\u00e9 \u00bb<\/em> &#8211; participation massive des citoyens \u00e0 cette marche symbolique et distribution de 2000 brochures informatives sur la violence \u00e0 l\u2019\u00e9gard des femmes mais surtout sur la traite des \u00eatres humains.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-19222\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download.jpg\" alt=\"\" width=\"701\" height=\"467\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download.jpg 960w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-300x200.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-768x512.jpg 768w\" sizes=\"(max-width: 701px) 100vw, 701px\" \/><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>3e action<\/strong> : Exposition de photos intitul\u00e9e <em>\u00ab Des v\u00e9rit\u00e9s non divulgu\u00e9es \u00bb <\/em>dans un caf\u00e9 du centre de la ville (le photographe est membre du club). L&rsquo;objectif principal \u00e9tait de lever le voile sur le sujet tabou des abus qui se produisent encore dans la soci\u00e9t\u00e9 moderne. De nombreux orateurs invit\u00e9s ont assist\u00e9 \u00e0 l&rsquo;\u00e9v\u00e9nement, notamment le chef du d\u00e9partement de police de Volos et la porte-parole du d\u00e9partement de police qui ont inform\u00e9 le public d&rsquo;une nouvelle ligne d&rsquo;assistance t\u00e9l\u00e9phonique (15990) sur la violence domestique. Certaines femmes &#8211; victimes de violence &#8211; ont trouv\u00e9 la force de partager avec le public leurs exp\u00e9riences traumatisantes. De plus, au cours de cette semaine, la Pr\u00e9sidente du Club a donn\u00e9 une interview \u00e0 une station WebTV locale populaire o\u00f9 elle a d\u00e9crit les objectifs du Soroptimist International et a d\u00e9taill\u00e9 les projets lanc\u00e9s par les clubs Soroptimist locaux sur le sujet de la violence \u00e0 l\u2019\u00e9gard des femmes.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-19226\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-3.jpg\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-3.jpg 720w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-3-300x225.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-3-320x240.jpg 320w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>4\u00e8me action<\/strong> : Un concert de guitare a eu lieu dans un b\u00e2timent historique illumin\u00e9 en orange gr\u00e2ce aux Soroptimist. L&rsquo;orchestre accompagn\u00e9 de deux chanteurs classiques a interpr\u00e9t\u00e9 pendant une heure et demie une vari\u00e9t\u00e9 de pi\u00e8ces musicales de c\u00e9l\u00e8bres compositeurs grecs. Des repr\u00e9sentants de toutes les autorit\u00e9s locales ont particip\u00e9 \u00e0 cet \u00e9v\u00e9nement.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19229\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4.jpg\" alt=\"\" width=\"699\" height=\"466\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4.jpg 1772w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4-300x200.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4-1024x682.jpg 1024w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4-768x512.jpg 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4-1536x1024.jpg 1536w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>5\u00e8me action<\/strong> : Les Soroptimist ont fait don des fonds r\u00e9colt\u00e9s lors de la vente des billets du concert (500 euros) au <em>\u00ab\u00a0Service social pour les femmes victimes de violence \u00bb<\/em> de la ville ; une organisation caritative qui vient en aide aux femmes et aux enfants.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Tous ces \u00e9v\u00e9nements ont b\u00e9n\u00e9fici\u00e9 d\u2019une large couverture m\u00e9diatique dans tous les journaux locaux, les stations de radio et les r\u00e9seaux sociaux\u00a0!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19232\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-5.jpg\" alt=\"\" width=\"702\" height=\"468\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-5.jpg 960w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-5-300x200.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-5-768x512.jpg 768w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soroptimist Club de Volos Thetis, Gr\u00e8ce Dans le cadre de la campagne \u00ab Oranger le monde \u00bb, les Soroptimist de Volos Thetis en Gr\u00e8ce ont initi\u00e9 5 actions cons\u00e9cutives afin [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":37628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[127,129],"tags":[188],"class_list":["post-19235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eradiquer-la-violence-a-legard-des-femmes","category-nouvelles","tag-eradiquer-la-violence-a-legard-des-femmes"],"acf":{"article_photo_de_couverture":false,"article_chapeau":"","article_contenu":[{"article_titre_du_paragraphe":"Soroptimist Club de Volos Thetis, Gr\u00e8ce","article_paragraphe":"<p>Dans le cadre de la campagne \u00ab Oranger le monde \u00bb, les Soroptimist de Volos Thetis en Gr\u00e8ce ont initi\u00e9 5 actions cons\u00e9cutives afin de sensibiliser la population sur les violences faites aux femmes et les diff\u00e9rentes formes de soutien qui peuvent \u00eatre apport\u00e9es :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>1\u00e8re action<\/strong> : Projection publique du film <em>\u00ab\u00a0Zenaida\u00a0\u00bb<\/em> \u00e0 l&rsquo;Universit\u00e9 de Thessalie, suivie d&rsquo;une discussion avec les \u00e9tudiants et le r\u00e9alisateur du film sur la question de la traite. Le lendemain, un atelier sur le tournage de films traitant de la violence a \u00e9t\u00e9 donn\u00e9 en pr\u00e9sence de nombreux \u00e9tudiants.<\/li>\n<\/ul>\n<table>\n<tbody>\n<tr>\n<td width=\"200\"><\/td>\n<td width=\"200\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19219\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-1-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-1-212x300.jpg 212w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-1.jpg 678w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/td>\n<td width=\"200\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul>\n<li><strong>2\u00e8me action<\/strong> : <em>\u00ab\u00a0Marche pour la libert\u00e9 \u00bb<\/em> &#8211; participation massive des citoyens \u00e0 cette marche symbolique et distribution de 2000 brochures informatives sur la violence \u00e0 l\u2019\u00e9gard des femmes mais surtout sur la traite des \u00eatres humains.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19222\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-300x200.jpg\" alt=\"\" width=\"701\" height=\"467\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-300x200.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-768x512.jpg 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download.jpg 960w\" sizes=\"(max-width: 701px) 100vw, 701px\" \/><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>3e action<\/strong> : Exposition de photos intitul\u00e9e <em>\u00ab Des v\u00e9rit\u00e9s non divulgu\u00e9es \u00bb <\/em>dans un caf\u00e9 du centre de la ville (le photographe est membre du club). L&rsquo;objectif principal \u00e9tait de lever le voile sur le sujet tabou des abus qui se produisent encore dans la soci\u00e9t\u00e9 moderne. De nombreux orateurs invit\u00e9s ont assist\u00e9 \u00e0 l&rsquo;\u00e9v\u00e9nement, notamment le chef du d\u00e9partement de police de Volos et la porte-parole du d\u00e9partement de police qui ont inform\u00e9 le public d&rsquo;une nouvelle ligne d&rsquo;assistance t\u00e9l\u00e9phonique (15990) sur la violence domestique. Certaines femmes &#8211; victimes de violence &#8211; ont trouv\u00e9 la force de partager avec le public leurs exp\u00e9riences traumatisantes. De plus, au cours de cette semaine, la Pr\u00e9sidente du Club a donn\u00e9 une interview \u00e0 une station WebTV locale populaire o\u00f9 elle a d\u00e9crit les objectifs du Soroptimist International et a d\u00e9taill\u00e9 les projets lanc\u00e9s par les clubs Soroptimist locaux sur le sujet de la violence \u00e0 l\u2019\u00e9gard des femmes.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19226\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-3-300x225.jpg\" alt=\"\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-3-300x225.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-3-320x240.jpg 320w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-3.jpg 720w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>4\u00e8me action<\/strong> : Un concert de guitare a eu lieu dans un b\u00e2timent historique illumin\u00e9 en orange gr\u00e2ce aux Soroptimist. L&rsquo;orchestre accompagn\u00e9 de deux chanteurs classiques a interpr\u00e9t\u00e9 pendant une heure et demie une vari\u00e9t\u00e9 de pi\u00e8ces musicales de c\u00e9l\u00e8bres compositeurs grecs. Des repr\u00e9sentants de toutes les autorit\u00e9s locales ont particip\u00e9 \u00e0 cet \u00e9v\u00e9nement.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19229\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4-300x200.jpg\" alt=\"\" width=\"699\" height=\"466\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4-300x200.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4-1024x682.jpg 1024w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4-768x512.jpg 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4-1536x1024.jpg 1536w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-4.jpg 1772w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>5\u00e8me action<\/strong> : Les Soroptimist ont fait don des fonds r\u00e9colt\u00e9s lors de la vente des billets du concert (500 euros) au <em>\u00ab\u00a0Service social pour les femmes victimes de violence \u00bb<\/em> de la ville ; une organisation caritative qui vient en aide aux femmes et aux enfants.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Tous ces \u00e9v\u00e9nements ont b\u00e9n\u00e9fici\u00e9 d\u2019une large couverture m\u00e9diatique dans tous les journaux locaux, les stations de radio et les r\u00e9seaux sociaux\u00a0!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19232\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-5-300x200.jpg\" alt=\"\" width=\"702\" height=\"468\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-5-300x200.jpg 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-5-768x512.jpg 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2020\/11\/download-5.jpg 960w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/p>\n","article_media_image":false,"article_media_video":""}],"article_trombinoscope":false,"article_video":"","article_evenements_sociaux":false,"article_auteur_texte":"<p>Par l&rsquo;\u00e9quipe du Programme du SIE<\/p>\n","article_nom_contact":"","article_email_contact":"","article_numero_contact":"","article_documents":false,"article_actualites_liees":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es - Soroptimist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es - Soroptimist\" \/>\n<meta property=\"og:description\" content=\"Soroptimist Club de Volos Thetis, Gr\u00e8ce Dans le cadre de la campagne \u00ab Oranger le monde \u00bb, les Soroptimist de Volos Thetis en Gr\u00e8ce ont initi\u00e9 5 actions cons\u00e9cutives afin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/\" \/>\n<meta property=\"og:site_name\" content=\"Soroptimist\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-04T06:20:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T09:17:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/download-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Virginie Racine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Virginie Racine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/\"},\"author\":{\"name\":\"Virginie Racine\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"headline\":\"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es\",\"datePublished\":\"2020-12-04T06:20:22+00:00\",\"dateModified\":\"2025-05-13T09:17:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/\"},\"wordCount\":465,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/download-2-1.jpg\",\"keywords\":[\"Eradiquer la violence \u00e0 l'\u00e9gard des femmes\"],\"articleSection\":[\"Eradiquer la violence \u00e0 l&#039;\u00e9gard des femmes\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/\",\"name\":\"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es - Soroptimist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/download-2-1.jpg\",\"datePublished\":\"2020-12-04T06:20:22+00:00\",\"dateModified\":\"2025-05-13T09:17:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/download-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/download-2-1.jpg\",\"width\":960,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/\",\"name\":\"Soroptimist\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\",\"name\":\"Virginie Racine\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/author\\\/adminsorop2k21\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es - Soroptimist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/","og_locale":"fr_FR","og_type":"article","og_title":"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es - Soroptimist","og_description":"Soroptimist Club de Volos Thetis, Gr\u00e8ce Dans le cadre de la campagne \u00ab Oranger le monde \u00bb, les Soroptimist de Volos Thetis en Gr\u00e8ce ont initi\u00e9 5 actions cons\u00e9cutives afin [&hellip;]","og_url":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/","og_site_name":"Soroptimist","article_published_time":"2020-12-04T06:20:22+00:00","article_modified_time":"2025-05-13T09:17:37+00:00","og_image":[{"width":960,"height":625,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/download-2-1.jpg","type":"image\/jpeg"}],"author":"Virginie Racine","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Virginie Racine","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/#article","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/"},"author":{"name":"Virginie Racine","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"headline":"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es","datePublished":"2020-12-04T06:20:22+00:00","dateModified":"2025-05-13T09:17:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/"},"wordCount":465,"commentCount":0,"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/download-2-1.jpg","keywords":["Eradiquer la violence \u00e0 l'\u00e9gard des femmes"],"articleSection":["Eradiquer la violence \u00e0 l&#039;\u00e9gard des femmes","Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/","url":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/","name":"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es - Soroptimist","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/#primaryimage"},"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/download-2-1.jpg","datePublished":"2020-12-04T06:20:22+00:00","dateModified":"2025-05-13T09:17:37+00:00","author":{"@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"breadcrumb":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/#primaryimage","url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/download-2-1.jpg","contentUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/download-2-1.jpg","width":960,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/www.soroptimisteurope.org\/fr\/societe-moderne-et-violence-a-legard-des-femmes-des-verites-non-divulguees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soroptimisteurope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Soci\u00e9t\u00e9 moderne et violence \u00e0 l\u2019\u00e9gard des femmes : des v\u00e9rit\u00e9s non divulgu\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.soroptimisteurope.org\/#website","url":"https:\/\/www.soroptimisteurope.org\/","name":"Soroptimist","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soroptimisteurope.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619","name":"Virginie Racine","url":"https:\/\/www.soroptimisteurope.org\/fr\/author\/adminsorop2k21\/"}]}},"_links":{"self":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/19235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/comments?post=19235"}],"version-history":[{"count":0,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/19235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media\/37628"}],"wp:attachment":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media?parent=19235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/categories?post=19235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/tags?post=19235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}