{"id":22676,"date":"2021-12-07T08:10:00","date_gmt":"2021-12-07T07:10:00","guid":{"rendered":"http:\/\/www.soroptimisteurope.org\/?p=22676"},"modified":"2025-05-13T11:18:15","modified_gmt":"2025-05-13T09:18:15","slug":"victory-hills","status":"publish","type":"post","link":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/","title":{"rendered":"\u201cVictory Hills\u201d"},"content":{"rendered":"<p>En mai 2020, les membres du Club de Sudurland (Islande) ont entam\u00e9 un projet d\u2019envergure qui r\u00e9pond \u00e0 plusieurs objectifs soroptimist\u00a0: l\u2019\u00e9radication de la violence envers les femmes, l\u2019autonomisation financi\u00e8re des femmes et l\u2019\u00e9galit\u00e9 des sexes. Pour apporter leur contribution durable \u00e0 la communaut\u00e9 locale d\u2019Islande du Sud, elles ont ouvert un centre de service et de soins pour des femmes victimes de violence domestique. Cet \u00e9tablissement dispense \u00e9galement une formation sur la violence bas\u00e9e sur le genre.<\/p>\n<p>&nbsp;<\/p>\n<p>Avec le projet <em>Victory Hills<\/em>, les Soroptimist de Sudurland rassemblent des acteurs r\u00e9gionaux et \u00e9tatiques, ainsi que des ONG afin d\u2019am\u00e9liorer les services, la sensibilisation et la coordination dans le combat contre la violence faite aux femmes. De l\u2019\u00e9laboration d\u00e9taill\u00e9e du projet et de son budget, \u00e0 la recherche de partenaires et de subventions, en passant par la formation de membres b\u00e9n\u00e9voles pour s\u2019occuper de la r\u00e9ception et de l\u2019accueil du centre, \u00e0 l\u2019engagement du personnel professionnel et aux actions de relations publiques, il a fallu dix mois aux Soroptimist islandaises pour jeter les bases de leur projet. Gr\u00e2ce \u00e0 l\u2019engagement sans faille des membres du club, le centre Victory Hills a ouvert ses portes le 20 mars 2021.<\/p>\n<p>&nbsp;<\/p>\n<p>Dans les premiers temps, il a fallu surmonter une certaine h\u00e9sitation de la part de la population f\u00e9minine locale \u00e0 utiliser le centre, mais les services sociaux, la police et le centre m\u00e9dical du sud de l\u2019Islande envoie fr\u00e9quemment et continuellement des patientes.<\/p>\n<p>&nbsp;<\/p>\n<p>Le club de Sudurland peut compter sur l\u2019Universit\u00e9 d\u2019Islande pour les aider \u00e0 mener une \u00e9valuation interne et externe, professionnelle et ind\u00e9pendante, pour obtenir des statistiques sur l\u2019utilisation et les avantages de leur projet. Cela doit \u00e9galement leur permettre d\u2019avoir une base solide pour de futures prises d\u00e9cisionnelles de la part des autorit\u00e9s locales et de leurs partenaires concernant le financement du centre <em>Victory Hills<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab\u00a0C&rsquo;est incroyable pour moi, en tant que victime de violence domestique, de pouvoir b\u00e9n\u00e9ficier d&rsquo;une th\u00e9rapie pour soigner mon traumatisme, non seulement gratuitement, mais ici dans ma ville natale et sans avoir \u00e0 faire des heures de route \u00e0 travers une montagne. Bravo !\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-22685\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement.jpg\" alt=\"\" width=\"632\" height=\"645\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement.jpg 1156w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement-294x300.jpg 294w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement-1002x1024.jpg 1002w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement-768x785.jpg 768w\" sizes=\"(max-width: 632px) 100vw, 632px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Club de Sudurland (Islande)<\/p>\n","protected":false},"author":5,"featured_media":38308,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[127,129],"tags":[188],"class_list":["post-22676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eradiquer-la-violence-a-legard-des-femmes","category-nouvelles","tag-eradiquer-la-violence-a-legard-des-femmes"],"acf":{"article_chapeau":"<p>Club de Sudurland (Islande)<\/p>\n","article_contenu":[{"article_titre_du_paragraphe":"","article_paragraphe":"<p>En mai 2020, les membres du Club de Sudurland (Islande) ont entam\u00e9 un projet d\u2019envergure qui r\u00e9pond \u00e0 plusieurs objectifs soroptimist\u00a0: l\u2019\u00e9radication de la violence envers les femmes, l\u2019autonomisation financi\u00e8re des femmes et l\u2019\u00e9galit\u00e9 des sexes. Pour apporter leur contribution durable \u00e0 la communaut\u00e9 locale d\u2019Islande du Sud, elles ont ouvert un centre de service et de soins pour des femmes victimes de violence domestique. Cet \u00e9tablissement dispense \u00e9galement une formation sur la violence bas\u00e9e sur le genre.<\/p>\n<p>&nbsp;<\/p>\n<p>Avec le projet <em>Victory Hills<\/em>, les Soroptimist de Sudurland rassemblent des acteurs r\u00e9gionaux et \u00e9tatiques, ainsi que des ONG afin d\u2019am\u00e9liorer les services, la sensibilisation et la coordination dans le combat contre la violence faite aux femmes. De l\u2019\u00e9laboration d\u00e9taill\u00e9e du projet et de son budget, \u00e0 la recherche de partenaires et de subventions, en passant par la formation de membres b\u00e9n\u00e9voles pour s\u2019occuper de la r\u00e9ception et de l\u2019accueil du centre, \u00e0 l\u2019engagement du personnel professionnel et aux actions de relations publiques, il a fallu dix mois aux Soroptimist islandaises pour jeter les bases de leur projet. Gr\u00e2ce \u00e0 l\u2019engagement sans faille des membres du club, le centre Victory Hills a ouvert ses portes le 20 mars 2021.<\/p>\n<p>&nbsp;<\/p>\n<p>Dans les premiers temps, il a fallu surmonter une certaine h\u00e9sitation de la part de la population f\u00e9minine locale \u00e0 utiliser le centre, mais les services sociaux, la police et le centre m\u00e9dical du sud de l\u2019Islande envoie fr\u00e9quemment et continuellement des patientes.<\/p>\n<p>&nbsp;<\/p>\n<p>Le club de Sudurland peut compter sur l\u2019Universit\u00e9 d\u2019Islande pour les aider \u00e0 mener une \u00e9valuation interne et externe, professionnelle et ind\u00e9pendante, pour obtenir des statistiques sur l\u2019utilisation et les avantages de leur projet. Cela doit \u00e9galement leur permettre d\u2019avoir une base solide pour de futures prises d\u00e9cisionnelles de la part des autorit\u00e9s locales et de leurs partenaires concernant le financement du centre <em>Victory Hills<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00ab\u00a0C&rsquo;est incroyable pour moi, en tant que victime de violence domestique, de pouvoir b\u00e9n\u00e9ficier d&rsquo;une th\u00e9rapie pour soigner mon traumatisme, non seulement gratuitement, mais ici dans ma ville natale et sans avoir \u00e0 faire des heures de route \u00e0 travers une montagne. Bravo !\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-22685\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement-294x300.jpg\" alt=\"\" width=\"632\" height=\"645\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement-294x300.jpg 294w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement-1002x1024.jpg 1002w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement-768x785.jpg 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/12\/tlchargement.jpg 1156w\" sizes=\"(max-width: 632px) 100vw, 632px\" \/><\/p>\n","article_media_image":false,"article_media_video":""}],"article_trombinoscope":false,"article_video":"","article_evenements_sociaux":false,"article_auteur_texte":"","article_nom_contact":"","article_email_contact":"","article_numero_contact":"","article_documents":false,"article_actualites_liees":false,"article_photo_de_couverture":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cVictory Hills\u201d - Soroptimist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cVictory Hills\u201d - Soroptimist\" \/>\n<meta property=\"og:description\" content=\"Club de Sudurland (Islande)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/\" \/>\n<meta property=\"og:site_name\" content=\"Soroptimist\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-07T07:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T09:18:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1070356980-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Virginie Racine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Virginie Racine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/\"},\"author\":{\"name\":\"Virginie Racine\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"headline\":\"\u201cVictory Hills\u201d\",\"datePublished\":\"2021-12-07T07:10:00+00:00\",\"dateModified\":\"2025-05-13T09:18:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/\"},\"wordCount\":382,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/istock-1070356980-1.jpg\",\"keywords\":[\"Eradiquer la violence \u00e0 l'\u00e9gard des femmes\"],\"articleSection\":[\"Eradiquer la violence \u00e0 l&#039;\u00e9gard des femmes\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/\",\"name\":\"\u201cVictory Hills\u201d - Soroptimist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/istock-1070356980-1.jpg\",\"datePublished\":\"2021-12-07T07:10:00+00:00\",\"dateModified\":\"2025-05-13T09:18:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/istock-1070356980-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/istock-1070356980-1.jpg\",\"width\":2121,\"height\":1414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/victory-hills\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cVictory Hills\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/\",\"name\":\"Soroptimist\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\",\"name\":\"Virginie Racine\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/author\\\/adminsorop2k21\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cVictory Hills\u201d - Soroptimist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/","og_locale":"fr_FR","og_type":"article","og_title":"\u201cVictory Hills\u201d - Soroptimist","og_description":"Club de Sudurland (Islande)","og_url":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/","og_site_name":"Soroptimist","article_published_time":"2021-12-07T07:10:00+00:00","article_modified_time":"2025-05-13T09:18:15+00:00","og_image":[{"width":2121,"height":1414,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1070356980-1.jpg","type":"image\/jpeg"}],"author":"Virginie Racine","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Virginie Racine","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/#article","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/"},"author":{"name":"Virginie Racine","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"headline":"\u201cVictory Hills\u201d","datePublished":"2021-12-07T07:10:00+00:00","dateModified":"2025-05-13T09:18:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/"},"wordCount":382,"commentCount":0,"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1070356980-1.jpg","keywords":["Eradiquer la violence \u00e0 l'\u00e9gard des femmes"],"articleSection":["Eradiquer la violence \u00e0 l&#039;\u00e9gard des femmes","Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/","url":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/","name":"\u201cVictory Hills\u201d - Soroptimist","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/#primaryimage"},"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1070356980-1.jpg","datePublished":"2021-12-07T07:10:00+00:00","dateModified":"2025-05-13T09:18:15+00:00","author":{"@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"breadcrumb":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/#primaryimage","url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1070356980-1.jpg","contentUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/istock-1070356980-1.jpg","width":2121,"height":1414},{"@type":"BreadcrumbList","@id":"https:\/\/www.soroptimisteurope.org\/fr\/victory-hills\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soroptimisteurope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"\u201cVictory Hills\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.soroptimisteurope.org\/#website","url":"https:\/\/www.soroptimisteurope.org\/","name":"Soroptimist","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soroptimisteurope.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619","name":"Virginie Racine","url":"https:\/\/www.soroptimisteurope.org\/fr\/author\/adminsorop2k21\/"}]}},"_links":{"self":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/22676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/comments?post=22676"}],"version-history":[{"count":0,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/22676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media\/38308"}],"wp:attachment":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media?parent=22676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/categories?post=22676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/tags?post=22676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}