{"id":24172,"date":"2022-06-30T13:12:31","date_gmt":"2022-06-30T12:12:31","guid":{"rendered":"http:\/\/www.soroptimisteurope.org\/?p=24172"},"modified":"2025-05-13T11:18:29","modified_gmt":"2025-05-13T09:18:29","slug":"la-brochure-des-meilleures-pratiques-2022-est-maintenant-disponible","status":"publish","type":"post","link":"https:\/\/www.soroptimisteurope.org\/fr\/la-brochure-des-meilleures-pratiques-2022-est-maintenant-disponible\/","title":{"rendered":"La Brochure des Meilleures Pratiques 2022 est maintenant disponible!"},"content":{"rendered":"<p>Chaque ann\u00e9e, le SIE d\u00e9cerne des prix aux\u00a0projets exceptionnels pour chacun des\u00a0objectifs du SIE: l\u2019\u00e9ducation, l\u2019autonomie financi\u00e8re, la violence \u00e0 l\u2019\u00e9gard des femmes, la sant\u00e9 et s\u00e9curit\u00e9 alimentaire, et le d\u00e9veloppement durable.<\/p>\n<p>Les Soroptimist peuvent\u00a0\u00eatre fi\u00e8res de ces projets\u00a0ph\u00e9nom\u00e9naux et par cons\u00e9quent du soutien apport\u00e9 \u00e0 des milliers de femmes.<\/p>\n<p>&nbsp;<\/p>\n<p>Les projets gagnants sont les suivants :<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PRIX SP\u00c9CIAL DE LA P\u00c9RIODE BIENNALE DU SIE 2021-2022<\/strong><br \/>\nUnion italienne<\/p>\n<p><em>Une oasis verte pour sauver les abeilles<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>MEILLEUR PROJET D\u2019UNION<\/strong><br \/>\nUnion italienne<\/p>\n<p><em>\u00c9ducation financi\u00e8re \u2013 Les femmes comptent<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>PRIX SP\u00c9CIAL NOUVEAUX MEMBRES &#038; VISIBILITE<\/strong><br \/>\nUnion autrichienne<\/p>\n<p><em>La route vers l\u2019\u00e9galit\u00e9<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE \u00c9DUCATION<\/strong><br \/>\nClub d\u2019Almere \u2013 PAYS-BAS, SURINAME &#038; CURA\u00c7AO<\/p>\n<p><em>L\u2019autonomie \u00e0 travers l\u2019\u00e9ducation pour des femmes vivant dans des refuges<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE AUTONOMIE FINANCI\u00c8RE<\/strong><br \/>\nClub de M\u00f6dling &#8211; AUTRICHE<\/p>\n<p><em>Des conf\u00e9rences de qualit\u00e9 propos\u00e9es par des femmes pendant la pand\u00e9mie de COVID-19<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE \u00c9RADICATION DE LA VIOLENCE \u00c0 L\u2019\u00c9GARD DES FEMMES<\/strong><br \/>\nClub de Kuwait &#8211; KOWE\u00cfT<\/p>\n<p><em>\u00ab\u00a0I stand with her\u00a0\u00bb &#8211; Orange Kuwait<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE SANT\u00c9<\/strong><br \/>\nClub de Cayenne \u2013 FRANCE<\/p>\n<p><em>Pr\u00e9vention de l\u2019AVC en Guyane\u00a0: \u00ab\u00a0Pran Swen Di To tch<\/em><em>\u00f2\u00a0\u00bb<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE D\u00c9VELOPPEMENT DURABLE<\/strong><br \/>\nClub de Bergamo &#8211; ITALIE<\/p>\n<p><em>Une approche visionnaire des d\u00e9chets de l\u2019a\u00e9roport (A\u00e9roport international de Bergame Orio al Serio)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Cliquez sur l\u2019ic\u00f4ne pour lire la brochure et d\u00e9couvrir les projets gagnants !<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/sie-bpa-brochure-fr-2022-final-bd-spread.pdf\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-24175\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr.png 911w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr-300x300.png 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr-150x150.png 150w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr-768x768.png 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaque ann\u00e9e, le SIE d\u00e9cerne des prix aux\u00a0projets exceptionnels pour chacun des\u00a0objectifs du SIE: l\u2019\u00e9ducation, l\u2019autonomie financi\u00e8re, la violence \u00e0 l\u2019\u00e9gard des femmes, la sant\u00e9 et s\u00e9curit\u00e9 alimentaire, et le [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":38675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[129],"tags":[],"class_list":["post-24172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"acf":{"article_photo_de_couverture":false,"article_chapeau":"","article_contenu":[{"article_titre_du_paragraphe":"","article_paragraphe":"<p>Chaque ann\u00e9e, le SIE d\u00e9cerne des prix aux\u00a0projets exceptionnels pour chacun des\u00a0objectifs du SIE: l\u2019\u00e9ducation, l\u2019autonomie financi\u00e8re, la violence \u00e0 l\u2019\u00e9gard des femmes, la sant\u00e9 et s\u00e9curit\u00e9 alimentaire, et le d\u00e9veloppement durable.<\/p>\n<p>Les Soroptimist peuvent\u00a0\u00eatre fi\u00e8res de ces projets\u00a0ph\u00e9nom\u00e9naux et par cons\u00e9quent du soutien apport\u00e9 \u00e0 des milliers de femmes.<\/p>\n<p>&nbsp;<\/p>\n<p>Les projets gagnants sont les suivants :<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PRIX SP\u00c9CIAL DE LA P\u00c9RIODE BIENNALE DU SIE 2021-2022<\/strong><br \/>\nUnion italienne<\/p>\n<p><em>Une oasis verte pour sauver les abeilles<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>MEILLEUR PROJET D\u2019UNION<\/strong><br \/>\nUnion italienne<\/p>\n<p><em>\u00c9ducation financi\u00e8re \u2013 Les femmes comptent<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>PRIX SP\u00c9CIAL NOUVEAUX MEMBRES &amp; VISIBILITE<\/strong><br \/>\nUnion autrichienne<\/p>\n<p><em>La route vers l\u2019\u00e9galit\u00e9<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE \u00c9DUCATION<\/strong><br \/>\nClub d\u2019Almere \u2013 PAYS-BAS, SURINAME &amp; CURA\u00c7AO<\/p>\n<p><em>L\u2019autonomie \u00e0 travers l\u2019\u00e9ducation pour des femmes vivant dans des refuges<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE AUTONOMIE FINANCI\u00c8RE<\/strong><br \/>\nClub de M\u00f6dling &#8211; AUTRICHE<\/p>\n<p><em>Des conf\u00e9rences de qualit\u00e9 propos\u00e9es par des femmes pendant la pand\u00e9mie de COVID-19<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE \u00c9RADICATION DE LA VIOLENCE \u00c0 L\u2019\u00c9GARD DES FEMMES<\/strong><br \/>\nClub de Kuwait &#8211; KOWE\u00cfT<\/p>\n<p><em>\u00ab\u00a0I stand with her\u00a0\u00bb &#8211; Orange Kuwait<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE SANT\u00c9<\/strong><br \/>\nClub de Cayenne \u2013 FRANCE<\/p>\n<p><em>Pr\u00e9vention de l\u2019AVC en Guyane\u00a0: \u00ab\u00a0Pran Swen Di To tch<\/em><em>\u00f2\u00a0\u00bb<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>GAGNANT DANS LA CAT\u00c9GORIE D\u00c9VELOPPEMENT DURABLE<\/strong><br \/>\nClub de Bergamo &#8211; ITALIE<\/p>\n<p><em>Une approche visionnaire des d\u00e9chets de l\u2019a\u00e9roport (A\u00e9roport international de Bergame Orio al Serio)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Cliquez sur l\u2019ic\u00f4ne pour lire la brochure et d\u00e9couvrir les projets gagnants !<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/sie-bpa-brochure-fr-2022-final-bd-spread.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-24175\" src=\"http:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr-300x300.png 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr-150x150.png 150w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr-768x768.png 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2022\/06\/cover-bpa-fr.png 911w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","article_media_image":false,"article_media_video":""}],"article_trombinoscope":false,"article_video":"","article_evenements_sociaux":false,"article_auteur_texte":"","article_nom_contact":"","article_email_contact":"","article_numero_contact":"","article_documents":false,"article_actualites_liees":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Brochure des Meilleures Pratiques 2022 est maintenant disponible! - Soroptimist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Brochure des Meilleures Pratiques 2022 est maintenant disponible! - Soroptimist\" \/>\n<meta property=\"og:description\" content=\"Chaque ann\u00e9e, le SIE d\u00e9cerne des prix aux\u00a0projets exceptionnels pour chacun des\u00a0objectifs du SIE: l\u2019\u00e9ducation, l\u2019autonomie financi\u00e8re, la violence \u00e0 l\u2019\u00e9gard des femmes, la sant\u00e9 et s\u00e9curit\u00e9 alimentaire, et le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/\" \/>\n<meta property=\"og:site_name\" content=\"Soroptimist\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-30T12:12:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T09:18:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/untitled-design-23-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Virginie Racine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Virginie Racine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/\"},\"author\":{\"name\":\"Virginie Racine\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"headline\":\"La Brochure des Meilleures Pratiques 2022 est maintenant disponible!\",\"datePublished\":\"2022-06-30T12:12:31+00:00\",\"dateModified\":\"2025-05-13T09:18:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/\"},\"wordCount\":283,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/untitled-design-23-1.png\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/\",\"name\":\"La Brochure des Meilleures Pratiques 2022 est maintenant disponible! - Soroptimist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/untitled-design-23-1.png\",\"datePublished\":\"2022-06-30T12:12:31+00:00\",\"dateModified\":\"2025-05-13T09:18:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/untitled-design-23-1.png\",\"contentUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/untitled-design-23-1.png\",\"width\":1250,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/the-brochure-of-the-best-practice-awards-2022-is-now-available\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Brochure des Meilleures Pratiques 2022 est maintenant disponible!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/\",\"name\":\"Soroptimist\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\",\"name\":\"Virginie Racine\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/author\\\/adminsorop2k21\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Brochure des Meilleures Pratiques 2022 est maintenant disponible! - Soroptimist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/","og_locale":"fr_FR","og_type":"article","og_title":"La Brochure des Meilleures Pratiques 2022 est maintenant disponible! - Soroptimist","og_description":"Chaque ann\u00e9e, le SIE d\u00e9cerne des prix aux\u00a0projets exceptionnels pour chacun des\u00a0objectifs du SIE: l\u2019\u00e9ducation, l\u2019autonomie financi\u00e8re, la violence \u00e0 l\u2019\u00e9gard des femmes, la sant\u00e9 et s\u00e9curit\u00e9 alimentaire, et le [&hellip;]","og_url":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/","og_site_name":"Soroptimist","article_published_time":"2022-06-30T12:12:31+00:00","article_modified_time":"2025-05-13T09:18:29+00:00","og_image":[{"width":1250,"height":300,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/untitled-design-23-1.png","type":"image\/png"}],"author":"Virginie Racine","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Virginie Racine","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/#article","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/"},"author":{"name":"Virginie Racine","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"headline":"La Brochure des Meilleures Pratiques 2022 est maintenant disponible!","datePublished":"2022-06-30T12:12:31+00:00","dateModified":"2025-05-13T09:18:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/"},"wordCount":283,"commentCount":0,"image":{"@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/untitled-design-23-1.png","articleSection":["Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/","url":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/","name":"La Brochure des Meilleures Pratiques 2022 est maintenant disponible! - Soroptimist","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/#primaryimage"},"image":{"@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/untitled-design-23-1.png","datePublished":"2022-06-30T12:12:31+00:00","dateModified":"2025-05-13T09:18:29+00:00","author":{"@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"breadcrumb":{"@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/#primaryimage","url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/untitled-design-23-1.png","contentUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/untitled-design-23-1.png","width":1250,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.soroptimisteurope.org\/the-brochure-of-the-best-practice-awards-2022-is-now-available\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soroptimisteurope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"La Brochure des Meilleures Pratiques 2022 est maintenant disponible!"}]},{"@type":"WebSite","@id":"https:\/\/www.soroptimisteurope.org\/#website","url":"https:\/\/www.soroptimisteurope.org\/","name":"Soroptimist","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soroptimisteurope.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619","name":"Virginie Racine","url":"https:\/\/www.soroptimisteurope.org\/fr\/author\/adminsorop2k21\/"}]}},"_links":{"self":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/24172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/comments?post=24172"}],"version-history":[{"count":0,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/24172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media\/38675"}],"wp:attachment":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media?parent=24172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/categories?post=24172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/tags?post=24172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}