{"id":25196,"date":"2023-02-03T17:38:10","date_gmt":"2023-02-03T16:38:10","guid":{"rendered":"https:\/\/www.soroptimisteurope.org\/?p=25196"},"modified":"2025-11-25T14:49:07","modified_gmt":"2025-11-25T13:49:07","slug":"journee-internationale-des-femmes-2023","status":"publish","type":"post","link":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/","title":{"rendered":"Journ\u00e9e internationale des femmes 2023"},"content":{"rendered":"<p>Pour la Journ\u00e9e internationale des femmes 2023 (JIF), Soroptimist International d&rsquo;Europe (SIE) propose de se concentrer sur les<strong> in\u00e9galit\u00e9s des genres<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>En invitant toutes les femmes \u00e0 porter deux chaussures diff\u00e9rentes le 8 mars, cette initiative permettra de sensibiliser davantage le public \u00e0 l&rsquo;in\u00e9galit\u00e9 mondiale persistante que les femmes subissent au quotidien.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Comme l&rsquo;ont d\u00e9clar\u00e9 les Nations unies, \u00ab\u00a0<a href=\"https:\/\/www.un.org\/sustainabledevelopment\/fr\/gender-equality\/\">l&rsquo;\u00e9galit\u00e9 des sexes n&rsquo;est pas seulement un droit fondamental, mais un fondement n\u00e9cessaire pour un monde pacifique, prosp\u00e8re et durable<\/a>\u00ab\u00a0. Les femmes repr\u00e9sentent actuellement 50% de la population mondiale. Pourtant, aujourd&rsquo;hui, pr\u00e8s de cette moiti\u00e9 de la population n&rsquo;a pas acc\u00e8s aux m\u00eames droits sociaux ou civils, aux m\u00eames opportunit\u00e9s \u00e9ducatives ou professionnelles, ou est victime de crimes en raison de son sexe.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c0 travers le slogan <strong>MARCHEZ DANS DES CHAUSSURES DIFF\u00c9RENTES POUR L&rsquo;\u00c9GALIT\u00c9 DES GENRES<\/strong>, nous invitons les Unions et les Clubs individuels \u00e0 diffuser largement la campagne en :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>publiant (site web et r\u00e9seaux sociaux) le visuel cr\u00e9\u00e9 pour la JIF 2023 et en mettant en \u00e9vidence trois faits d&rsquo;in\u00e9galit\u00e9 qui touchent leur pays. Vous trouverez ci-dessous des donn\u00e9es sur des exemples d&rsquo;in\u00e9galit\u00e9s en Europe et dans le monde\u00a0;<\/li>\n<li>imprimant et distribuant localement le flyer A5 (universit\u00e9s, espaces de coworking, salles de sport, magasins, etc.)\u00a0;<\/li>\n<li>informant les m\u00e9dias locaux;<\/li>\n<li>invitant toutes les autres organisations de femmes, les politiciens, etc. \u00e0 participer en portant deux chaussures diff\u00e9rentes le 8 mars.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>Cette initiative peut \u00eatre int\u00e9gr\u00e9e dans les plans que votre Union ou votre Club individuel a d\u00e9j\u00e0 pr\u00e9vus.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Comme pour la campagne READ THE SIGNS, le visuel sera disponible en plusieurs formats sur la plateforme CANVA et pour l&rsquo;impression du flyer A5 nous vous proposons un fichier InDesign et\/ou CANVA. Le slogan sera ainsi facile \u00e0 adapter dans votre langue nationale.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-25210\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr.png\" alt=\"\" width=\"650\" height=\"459\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr.png 2000w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr-300x212.png 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr-1024x722.png 1024w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr-768x541.png 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr-1536x1083.png 1536w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Nous vous invitons \u00e9galement \u00e0 soutenir notre pr\u00e9sence sur les r\u00e9seaux sociaux le 8 mars en encourageant vos membres \u00e0 se filmer en train de marcher avec deux chaussures diff\u00e9rentes pour sensibiliser aux in\u00e9galit\u00e9s que les femmes rencontrent au quotidien et \u00e0 le poster en ligne :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Utilisez le format de Story ou de Reel sur Instagram (1080 x 1920 px) pour filmer;<\/li>\n<li>Publiez sur les r\u00e9seaux sociaux de votre Union\/club;<\/li>\n<li>Taguez SIE @soroptimisteurope sur Instagram et @SoroptimistInternationalofEurope sur Facebook;<\/li>\n<li>Utilisez les hashtags #soroptimisteurope #westandupforwomen #equality #internationalwomensday #womensrights<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Pour la Journ\u00e9e internationale des femmes 2023 (JIF), Soroptimist International d&rsquo;Europe (SIE) propose de se concentrer sur les in\u00e9galit\u00e9s des genres. &nbsp; En invitant toutes les femmes \u00e0 porter deux [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":38973,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[120,129,130],"tags":[189,190],"class_list":["post-25196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-advocacy-fr","category-nouvelles","category-autonomie-financiere","tag-autonomie-financiere","tag-advocacy-fr"],"acf":{"article_photo_de_couverture":{"ID":25230,"id":25230,"title":"IWD 2023 - (1250 \u00d7 300px) (2)","filename":"iwd-2023-1250-300px-2.png","filesize":48847,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-1250-300px-2.png","link":"https:\/\/www.soroptimisteurope.org\/fr\/iwd-2023-1250-x-300px-2\/","alt":"","author":"3","description":"","caption":"","name":"iwd-2023-1250-x-300px-2","status":"inherit","uploaded_to":0,"date":"2023-02-15 09:31:35","modified":"2023-02-15 09:31:35","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.soroptimisteurope.org\/wp-content\/plugins\/media-library-assistant\/images\/crystal\/image.png","width":1250,"height":300,"sizes":{"thumbnail":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-1250-300px-2-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-1250-300px-2-300x72.png","medium-width":300,"medium-height":72,"medium_large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-1250-300px-2-768x184.png","medium_large-width":768,"medium_large-height":184,"large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-1250-300px-2-1024x246.png","large-width":800,"large-height":192,"1536x1536":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-1250-300px-2.png","1536x1536-width":1250,"1536x1536-height":300,"2048x2048":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-1250-300px-2.png","2048x2048-width":1250,"2048x2048-height":300}},"article_chapeau":"","article_contenu":[{"article_titre_du_paragraphe":"","article_paragraphe":"<p>Pour la Journ\u00e9e internationale des femmes 2023 (JIF), Soroptimist International d&rsquo;Europe (SIE) propose de se concentrer sur les<strong> in\u00e9galit\u00e9s des genres<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>En invitant toutes les femmes \u00e0 porter deux chaussures diff\u00e9rentes le 8 mars, cette initiative permettra de sensibiliser davantage le public \u00e0 l&rsquo;in\u00e9galit\u00e9 mondiale persistante que les femmes subissent au quotidien.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Comme l&rsquo;ont d\u00e9clar\u00e9 les Nations unies, \u00ab\u00a0<a href=\"https:\/\/www.un.org\/sustainabledevelopment\/fr\/gender-equality\/\">l&rsquo;\u00e9galit\u00e9 des sexes n&rsquo;est pas seulement un droit fondamental, mais un fondement n\u00e9cessaire pour un monde pacifique, prosp\u00e8re et durable<\/a>\u00ab\u00a0. Les femmes repr\u00e9sentent actuellement 50% de la population mondiale. Pourtant, aujourd&rsquo;hui, pr\u00e8s de cette moiti\u00e9 de la population n&rsquo;a pas acc\u00e8s aux m\u00eames droits sociaux ou civils, aux m\u00eames opportunit\u00e9s \u00e9ducatives ou professionnelles, ou est victime de crimes en raison de son sexe.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c0 travers le slogan <strong>MARCHEZ DANS DES CHAUSSURES DIFF\u00c9RENTES POUR L&rsquo;\u00c9GALIT\u00c9 DES GENRES<\/strong>, nous invitons les Unions et les Clubs individuels \u00e0 diffuser largement la campagne en :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>publiant (site web et r\u00e9seaux sociaux) le visuel cr\u00e9\u00e9 pour la JIF 2023 et en mettant en \u00e9vidence trois faits d&rsquo;in\u00e9galit\u00e9 qui touchent leur pays. Vous trouverez ci-dessous des donn\u00e9es sur des exemples d&rsquo;in\u00e9galit\u00e9s en Europe et dans le monde\u00a0;<\/li>\n<li>imprimant et distribuant localement le flyer A5 (universit\u00e9s, espaces de coworking, salles de sport, magasins, etc.)\u00a0;<\/li>\n<li>informant les m\u00e9dias locaux;<\/li>\n<li>invitant toutes les autres organisations de femmes, les politiciens, etc. \u00e0 participer en portant deux chaussures diff\u00e9rentes le 8 mars.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>Cette initiative peut \u00eatre int\u00e9gr\u00e9e dans les plans que votre Union ou votre Club individuel a d\u00e9j\u00e0 pr\u00e9vus.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Comme pour la campagne READ THE SIGNS, le visuel sera disponible en plusieurs formats sur la plateforme CANVA et pour l&rsquo;impression du flyer A5 nous vous proposons un fichier InDesign et\/ou CANVA. Le slogan sera ainsi facile \u00e0 adapter dans votre langue nationale.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-25210\" src=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr-300x212.png\" alt=\"\" width=\"650\" height=\"459\" srcset=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr-300x212.png 300w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr-1024x722.png 1024w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr-768x541.png 768w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr-1536x1083.png 1536w, https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2023\/02\/iwd-2023-flyer-a5-fr.png 2000w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Nous vous invitons \u00e9galement \u00e0 soutenir notre pr\u00e9sence sur les r\u00e9seaux sociaux le 8 mars en encourageant vos membres \u00e0 se filmer en train de marcher avec deux chaussures diff\u00e9rentes pour sensibiliser aux in\u00e9galit\u00e9s que les femmes rencontrent au quotidien et \u00e0 le poster en ligne :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Utilisez le format de Story ou de Reel sur Instagram (1080 x 1920 px) pour filmer;<\/li>\n<li>Publiez sur les r\u00e9seaux sociaux de votre Union\/club;<\/li>\n<li>Taguez SIE @soroptimisteurope sur Instagram et @SoroptimistInternationalofEurope sur Facebook;<\/li>\n<li>Utilisez les hashtags #soroptimisteurope #westandupforwomen #equality #internationalwomensday #womensrights<\/li>\n<\/ul>\n","article_media_image":false,"article_media_video":""}],"article_trombinoscope":false,"article_video":"","article_evenements_sociaux":false,"article_auteur_texte":"","article_nom_contact":"","article_email_contact":"","article_numero_contact":"","article_documents":false,"article_actualites_liees":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journ\u00e9e internationale des femmes 2023 - Soroptimist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journ\u00e9e internationale des femmes 2023 - Soroptimist\" \/>\n<meta property=\"og:description\" content=\"Pour la Journ\u00e9e internationale des femmes 2023 (JIF), Soroptimist International d&rsquo;Europe (SIE) propose de se concentrer sur les in\u00e9galit\u00e9s des genres. &nbsp; En invitant toutes les femmes \u00e0 porter deux [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Soroptimist\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-03T16:38:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T13:49:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/iwd-2023-1250-300px-2-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Virginie Racine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Virginie Racine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/\"},\"author\":{\"name\":\"Virginie Racine\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"headline\":\"Journ\u00e9e internationale des femmes 2023\",\"datePublished\":\"2023-02-03T16:38:10+00:00\",\"dateModified\":\"2025-11-25T13:49:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/\"},\"wordCount\":418,\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/iwd-2023-1250-300px-2-1.png\",\"keywords\":[\"Autonomie financi\u00e8re\",\"Advocacy\"],\"articleSection\":[\"Advocacy\",\"Nouvelles\",\"Autonomie financi\u00e8re\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/\",\"name\":\"Journ\u00e9e internationale des femmes 2023 - Soroptimist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/iwd-2023-1250-300px-2-1.png\",\"datePublished\":\"2023-02-03T16:38:10+00:00\",\"dateModified\":\"2025-11-25T13:49:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/iwd-2023-1250-300px-2-1.png\",\"contentUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/iwd-2023-1250-300px-2-1.png\",\"width\":1250,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/journee-internationale-des-femmes-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journ\u00e9e internationale des femmes 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/\",\"name\":\"Soroptimist\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/71cb5ee8dc72773ed419609bf2274619\",\"name\":\"Virginie Racine\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/author\\\/adminsorop2k21\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journ\u00e9e internationale des femmes 2023 - Soroptimist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Journ\u00e9e internationale des femmes 2023 - Soroptimist","og_description":"Pour la Journ\u00e9e internationale des femmes 2023 (JIF), Soroptimist International d&rsquo;Europe (SIE) propose de se concentrer sur les in\u00e9galit\u00e9s des genres. &nbsp; En invitant toutes les femmes \u00e0 porter deux [&hellip;]","og_url":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/","og_site_name":"Soroptimist","article_published_time":"2023-02-03T16:38:10+00:00","article_modified_time":"2025-11-25T13:49:07+00:00","og_image":[{"width":1250,"height":300,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/iwd-2023-1250-300px-2-1.png","type":"image\/png"}],"author":"Virginie Racine","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Virginie Racine"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/#article","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/"},"author":{"name":"Virginie Racine","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"headline":"Journ\u00e9e internationale des femmes 2023","datePublished":"2023-02-03T16:38:10+00:00","dateModified":"2025-11-25T13:49:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/"},"wordCount":418,"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/iwd-2023-1250-300px-2-1.png","keywords":["Autonomie financi\u00e8re","Advocacy"],"articleSection":["Advocacy","Nouvelles","Autonomie financi\u00e8re"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/","url":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/","name":"Journ\u00e9e internationale des femmes 2023 - Soroptimist","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/iwd-2023-1250-300px-2-1.png","datePublished":"2023-02-03T16:38:10+00:00","dateModified":"2025-11-25T13:49:07+00:00","author":{"@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619"},"breadcrumb":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/#primaryimage","url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/iwd-2023-1250-300px-2-1.png","contentUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/04\/iwd-2023-1250-300px-2-1.png","width":1250,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.soroptimisteurope.org\/fr\/journee-internationale-des-femmes-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soroptimisteurope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Journ\u00e9e internationale des femmes 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.soroptimisteurope.org\/#website","url":"https:\/\/www.soroptimisteurope.org\/","name":"Soroptimist","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soroptimisteurope.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/71cb5ee8dc72773ed419609bf2274619","name":"Virginie Racine","url":"https:\/\/www.soroptimisteurope.org\/fr\/author\/adminsorop2k21\/"}]}},"_links":{"self":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/25196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/comments?post=25196"}],"version-history":[{"count":0,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/25196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media\/38973"}],"wp:attachment":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media?parent=25196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/categories?post=25196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/tags?post=25196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}