{"id":51348,"date":"2025-10-29T15:33:23","date_gmt":"2025-10-29T14:33:23","guid":{"rendered":"https:\/\/www.soroptimisteurope.org\/?p=51348"},"modified":"2025-11-25T14:49:02","modified_gmt":"2025-11-25T13:49:02","slug":"read-the-signs-2025","status":"publish","type":"post","link":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/","title":{"rendered":"\u00ab\u00a0READ THE SIGNS\u00a0\u00bb 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"51348\" class=\"elementor elementor-51348 elementor-51299\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a3491b e-flex e-con-boxed e-con e-parent\" data-id=\"0a3491b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4627a2d elementor-widget elementor-widget-text-editor\" data-id=\"4627a2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #ff6600;\"><strong>Tirer parti des enseignements de l&rsquo;ann\u00e9e derni\u00e8re<\/strong><\/span><\/h4><p>La campagne de l&rsquo;ann\u00e9e derni\u00e8re nous a permis d&rsquo;apprendre \u00e9norm\u00e9ment gr\u00e2ce \u00e0 nos webinaires, au cours desquels des experts ont partag\u00e9 des id\u00e9es pratiques et des \u00ab\u00a0meilleurs conseils\u00a0\u00bb qui restent tr\u00e8s pertinents aujourd&rsquo;hui. Ces ressources sont toujours disponibles et m\u00e9ritent d&rsquo;\u00eatre revisit\u00e9es dans<a style=\"color: #3366ff;\" href=\"https:\/\/extranet.soroptimisteurope.org\/sieextranet\/pages\/login\/login.jsf\" target=\"_blank\" rel=\"noopener\"><strong> l&rsquo;espace membre de t\u00e9l\u00e9chargement du SIE<\/strong><\/a> car elles fournissent des outils concrets de sensibilisation, de pr\u00e9vention et d&rsquo;action.<\/p><p>\u00a0<\/p><h4><span style=\"color: #ff6600;\"><strong>Apprendre des experts et des survivants<\/strong><\/span><\/h4><p>D\u00e9but septembre, les Soroptimist ont eu l&rsquo;occasion d&rsquo;approfondir ces connaissances en \u00e9coutant le professeur Olga Jurasz lors du webinaire du SIE intitul\u00e9 \u00ab\u00a0<em>Technology-Facilitated Violence Against Women : Combler les lacunes dans les r\u00e9ponses juridiques et politiques<\/em>\u00ab\u00a0. En tant que directrice du <span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/cpwo.open.ac.uk\/\" target=\"_blank\" rel=\"noopener\"><strong>Centre pour la protection des femmes en ligne, <\/strong><\/a><\/span>elle a organis\u00e9 la premi\u00e8re conf\u00e9rence annuelle \u00e0 l&rsquo;Open University de Londres, \u00e0 laquelle j&rsquo;ai eu l&rsquo;honneur de participer.<\/p><p>\u00a0<\/p><p>Lors de la conf\u00e9rence, la r\u00e9alisatrice Patricia Franquesa a pr\u00e9sent\u00e9 son documentaire prim\u00e9 : \u00ab\u00a0My Sextortion Diary\u00a0\u00bb. Son histoire personnelle de chantage num\u00e9rique et de r\u00e9silience a rappel\u00e9 avec force que derri\u00e8re chaque statistique se cache une histoire de traumatisme, de r\u00e9silience et de besoin urgent de justice. \u00ab\u00a0Pati\u00a0\u00bb a d\u00e9cid\u00e9 d&rsquo;utiliser ses comp\u00e9tences cin\u00e9matographiques pour agir, en prenant sa d\u00e9fense et celle des autres.<\/p><p>\u00a0<\/p><p>Les histoires de cyberviolence sont infinies, ce qui rend la campagne soroptimist \u00ab\u00a0READ THE SIGNS\u00a0\u00bb plus pertinente que jamais, alors faisons tous en sorte que le monde virtuel soit un endroit s\u00fbr pour les femmes et les filles.<\/p><p>\u00a0<\/p><h4><span style=\"color: #ff6600;\"><strong>L&rsquo;importance de la cyberviolence<\/strong><\/span><\/h4><p>La cyberviolence n&rsquo;est pas un probl\u00e8me secondaire ou \u00ab\u00a0virtuel\u00a0\u00bb ; c&rsquo;est une menace profonde pour l&rsquo;\u00e9galit\u00e9, la libert\u00e9 d&rsquo;expression et la d\u00e9mocratie. Elle refl\u00e8te les sch\u00e9mas de la violence domestique, du pouvoir et du contr\u00f4le, de l&rsquo;escalade, de la culpabilisation des victimes et de l&rsquo;\u00e9chec des institutions, mais avec une port\u00e9e encore plus grande et un caract\u00e8re in\u00e9luctable. Les abus en ligne suivent les femmes chez elles, sur leur lieu de travail et dans leur vie priv\u00e9e, r\u00e9duisant souvent leur voix au silence.<\/p><p>\u00a0<\/p><p>Les lois doivent reconna\u00eetre la cyberviolence comme un d\u00e9lit distinct ; les survivantes ont besoin d&rsquo;un soutien accessible et financ\u00e9 par les pouvoirs publics ; la police et les tribunaux doivent \u00eatre form\u00e9s ; et les plateformes doivent \u00eatre tenues responsables des choix de conception qui favorisent les abus. La pr\u00e9vention passe \u00e9galement par l&rsquo;\u00e9ducation d\u00e8s le plus jeune \u00e2ge, l&rsquo;enseignement du consentement, de l&#8217;empathie et de l&rsquo;\u00e9galit\u00e9, les gar\u00e7ons et les hommes devenant des alli\u00e9s et des d\u00e9fenseurs de la cause.<\/p><p>\u00a0<\/p><p>Notre message est clair : les mesures volontaires ne suffisent pas. <strong>\u00ab\u00a0READ THE SIGNS\u00a0\u00bb 2025<\/strong> est un appel \u00e0 la mise en place de cadres juridiques, de solutions ax\u00e9es sur les survivants et d&rsquo;une action collective.<\/p><p>\u00a0<\/p><p>Chaque femme a le droit de vivre, de s&rsquo;exprimer et de s&rsquo;\u00e9panouir en ligne comme hors ligne, sans crainte.<\/p><p>\u00a0<\/p><p style=\"text-align: right;\">Par Rita Nogueira Ramos,<\/p><p style=\"text-align: right;\">Vice-pr\u00e9sidente Lobbying du SIE 2024-2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd793cc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bd793cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2a9485 e-flex e-con-boxed e-con e-parent\" data-id=\"a2a9485\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-187193c elementor-widget elementor-widget-heading\" data-id=\"187193c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\"Sextortion Diary\" par Patricia Franquesa<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-190206d e-grid e-con-boxed e-con e-parent\" data-id=\"190206d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af8773f elementor-widget elementor-widget-text-editor\" data-id=\"af8773f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>13 novembre \u00e0 18h CET sur ZOOM<\/strong><\/p><p>Rejoignez-nous pour un webinaire sur le film <strong>\u00ab\u00a0SEXTORTION DIARY\u00a0\u00bb de Patricia Franquesa<\/strong>, dans le cadre des pr\u00e9parations \u00e0 la campagne \u00ab\u00a0Read the Signs\u00a0\u00bb.<\/p><p>Patricia Franquesa est une r\u00e9alisatrice espagnole, fondatrice de Gadea Films. Un jour, alors qu\u2019elle \u00e9tait dans un caf\u00e9, son ordinateur portable a \u00e9t\u00e9 vol\u00e9. Peu apr\u00e8s, un hacker a commenc\u00e9 \u00e0 la menacer de publier ses photos intimes si elle ne payait pas une grosse somme d\u2019argent. Pendant un certain temps, elle a tent\u00e9 de chercher de l\u2019aide, s\u2019est adress\u00e9e \u00e0 la police, a parl\u00e9 du probl\u00e8me \u00e0 ses amis et a beaucoup souffert, isol\u00e9e chez elle. Un jour, apr\u00e8s avoir continu\u00e9 \u00e0 subir le chantage, elle a pris une d\u00e9cision radicale : publier elle-m\u00eame ses photos intimes. Le film a re\u00e7u plusieurs r\u00e9compenses, notamment le Prix Gaud\u00ed du meilleur documentaire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87192ef elementor-align-center elementor-widget elementor-widget-button\" data-id=\"87192ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/us06web.zoom.us\/j\/86511890403\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Rejoignez le webinaire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 l&rsquo;occasion du lancement de \u00ab\u00a0READ THE SIGNS\u00a0\u00bb pour pr\u00e9venir la cyberviolence 2025, nous avan\u00e7ons sur des bases plus solides que jamais. Je suis convaincue que nous sommes d\u00e9sormais mieux pr\u00e9par\u00e9es \u00e0 affronter les r\u00e9alit\u00e9s en constante \u00e9volution des violences en ligne. <\/p>\n","protected":false},"author":3,"featured_media":50991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[120,127,129],"tags":[188,190],"class_list":["post-51348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-advocacy-fr","category-eradiquer-la-violence-a-legard-des-femmes","category-nouvelles","tag-eradiquer-la-violence-a-legard-des-femmes","tag-advocacy-fr"],"acf":{"article_actualites_liees":false,"article_documents":false,"article_email_contact":"","article_evenements_sociaux":false,"article_nom_contact":"","article_numero_contact":"","article_photo_de_couverture":{"ID":51122,"id":51122,"title":"RTS 2025 Banner EN","filename":"RTS-2025-Banner-EN-scaled.png","filesize":121892,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2025-Banner-EN-scaled.png","link":"https:\/\/www.soroptimisteurope.org\/fr\/what-we-do-2\/advocacy\/rts-2025-banner-en\/","alt":"","author":"3","description":"","caption":"","name":"rts-2025-banner-en","status":"inherit","uploaded_to":47642,"date":"2025-10-21 21:06:38","modified":"2025-10-21 21:06:38","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.soroptimisteurope.org\/wp-content\/plugins\/media-library-assistant\/images\/crystal\/image.png","width":2560,"height":1054,"sizes":{"thumbnail":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2025-Banner-EN-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2025-Banner-EN-300x124.png","medium-width":300,"medium-height":124,"medium_large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2025-Banner-EN-768x316.png","medium_large-width":768,"medium_large-height":316,"large":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2025-Banner-EN-1024x422.png","large-width":800,"large-height":330,"1536x1536":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2025-Banner-EN-1536x632.png","1536x1536-width":1536,"1536x1536-height":632,"2048x2048":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2025-Banner-EN-2048x843.png","2048x2048-width":2048,"2048x2048-height":843}},"article_trombinoscope":false,"article_video":"","article_auteur_texte":"<p>Rita Nogueira Ramos<\/p>\n<p>SIE Vice-pr\u00e9sidente de la d\u00e9fense des int\u00e9r\u00eats 2024-2025<\/p>\n","article_chapeau":"<p>\u00c0 l'occasion du lancement de \"READ THE SIGNS\" pour pr\u00e9venir la cyberviolence 2025, nous avan\u00e7ons sur des bases plus solides que jamais. Je suis convaincue que nous sommes d\u00e9sormais mieux pr\u00e9par\u00e9es \u00e0 affronter les r\u00e9alit\u00e9s en constante \u00e9volution des violences en ligne. <\/p>\n","article_contenu":[{"article_titre_du_paragraphe":"","article_paragraphe":"<p><strong>Tirer parti des enseignements de l&rsquo;ann\u00e9e derni\u00e8re<\/strong><\/p>\n<p>La campagne de l&rsquo;ann\u00e9e derni\u00e8re nous a permis d&rsquo;apprendre \u00e9norm\u00e9ment gr\u00e2ce \u00e0 nos webinaires, au cours desquels des experts ont partag\u00e9 des id\u00e9es pratiques et des \u00ab\u00a0meilleurs conseils\u00a0\u00bb qui restent tr\u00e8s pertinents aujourd&rsquo;hui. Ces ressources sont toujours disponibles et m\u00e9ritent d&rsquo;\u00eatre consult\u00e9es dans l&rsquo;espace membres du t\u00e9l\u00e9chargement de la SIE, car elles fournissent des outils concrets de sensibilisation, de pr\u00e9vention et d&rsquo;action.<\/p>\n<p><strong>Apprendre des experts et des survivants<\/strong><\/p>\n<p>D\u00e9but septembre, les Soroptimistes ont eu l&rsquo;occasion d&rsquo;approfondir ces connaissances en \u00e9coutant le professeur Olga Jurasz lors du webinaire du SIE intitul\u00e9 \u00ab\u00a0<em>Technology-Facilitated Violence Against Women : Combler les lacunes dans les r\u00e9ponses juridiques et politiques<\/em>\u00ab\u00a0. En tant que directrice du Centre pour la protection des femmes en ligne, elle a organis\u00e9 la premi\u00e8re conf\u00e9rence annuelle \u00e0 l&rsquo;Open University de Londres, \u00e0 laquelle j&rsquo;ai eu l&rsquo;honneur de participer.<\/p>\n<p>Lors de la conf\u00e9rence, la r\u00e9alisatrice Patricia Franquesa a pr\u00e9sent\u00e9 son documentaire prim\u00e9 : \u00ab\u00a0My Sextortion Diary\u00a0\u00bb. Son histoire personnelle de chantage num\u00e9rique et de r\u00e9silience a rappel\u00e9 avec force que derri\u00e8re chaque statistique se cache une histoire de traumatisme, de r\u00e9silience et de besoin urgent de justice. \u00ab\u00a0Pati\u00a0\u00bb a d\u00e9cid\u00e9 d&rsquo;utiliser ses comp\u00e9tences cin\u00e9matographiques pour agir, en prenant sa d\u00e9fense et celle des autres.<\/p>\n<p>Les histoires de cyberviolence sont infinies, ce qui rend les soroptimistes LISEZ LES SIGNES plus pertinents que jamais, alors faisons tous en sorte que le monde virtuel soit un endroit s\u00fbr pour les femmes et les filles.<\/p>\n<p><strong>L&rsquo;importance de la cyberviolence<\/strong><\/p>\n<p>La cyberviolence n&rsquo;est pas un probl\u00e8me secondaire ou \u00ab\u00a0virtuel\u00a0\u00bb ; c&rsquo;est une menace profonde pour l&rsquo;\u00e9galit\u00e9, la libert\u00e9 d&rsquo;expression et la d\u00e9mocratie. Elle refl\u00e8te les sch\u00e9mas de la violence domestique, du pouvoir et du contr\u00f4le, de l&rsquo;escalade, de la culpabilisation des victimes et de l&rsquo;\u00e9chec des institutions, mais avec une port\u00e9e encore plus grande et un caract\u00e8re in\u00e9luctable. Les abus en ligne suivent les femmes chez elles, sur leur lieu de travail et dans leur vie priv\u00e9e, r\u00e9duisant souvent leur voix au silence.<\/p>\n<p>Les lois doivent reconna\u00eetre la cyberviolence comme un d\u00e9lit distinct ; les survivantes ont besoin d&rsquo;un soutien accessible et financ\u00e9 par les pouvoirs publics ; la police et les tribunaux doivent \u00eatre form\u00e9s ; et les plateformes doivent \u00eatre tenues responsables des choix de conception qui favorisent les abus. La pr\u00e9vention passe \u00e9galement par l&rsquo;\u00e9ducation d\u00e8s le plus jeune \u00e2ge, l&rsquo;enseignement du consentement, de l&#8217;empathie et de l&rsquo;\u00e9galit\u00e9, les gar\u00e7ons et les hommes devenant des alli\u00e9s et des d\u00e9fenseurs de la cause.<\/p>\n<p>Notre message est clair : les mesures volontaires ne suffisent pas. LISEZ LES SIGNES 2025 est un appel \u00e0 la mise en place de cadres juridiques, de solutions ax\u00e9es sur les survivants et d&rsquo;une action collective.<\/p>\n<p>Chaque femme a le droit de vivre, de s&rsquo;exprimer et de s&rsquo;\u00e9panouir en ligne comme hors ligne, sans crainte.<\/p>\n","article_media_image":false,"article_media_video":""}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;READ THE SIGNS&quot; 2025 - Soroptimist<\/title>\n<meta name=\"description\" content=\"Lire les signes 2025 lutte contre la cyberviolence. Apprenez \u00e0 rep\u00e9rer, pr\u00e9venir et agir. Ensemble, nous pouvons rendre le monde num\u00e9rique s\u00fbr pour les femmes et les filles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;READ THE SIGNS&quot; 2025 - Soroptimist\" \/>\n<meta property=\"og:description\" content=\"Lire les signes 2025 lutte contre la cyberviolence. Apprenez \u00e0 rep\u00e9rer, pr\u00e9venir et agir. Ensemble, nous pouvons rendre le monde num\u00e9rique s\u00fbr pour les femmes et les filles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Soroptimist\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-29T14:33:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T13:49:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2024-Banner-FR-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1054\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Soroptimist\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Soroptimist\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/\"},\"author\":{\"name\":\"Soroptimist\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/704fb842a150c870ec736ee629ee7e24\"},\"headline\":\"\u00ab\u00a0READ THE SIGNS\u00a0\u00bb 2025\",\"datePublished\":\"2025-10-29T14:33:23+00:00\",\"dateModified\":\"2025-11-25T13:49:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/\"},\"wordCount\":702,\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/RTS-2024-Banner-FR-scaled.png\",\"keywords\":[\"Eradiquer la violence \u00e0 l'\u00e9gard des femmes\",\"Advocacy\"],\"articleSection\":[\"Advocacy\",\"Eradiquer la violence \u00e0 l&#039;\u00e9gard des femmes\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/\",\"name\":\"\\\"READ THE SIGNS\\\" 2025 - Soroptimist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/RTS-2024-Banner-FR-scaled.png\",\"datePublished\":\"2025-10-29T14:33:23+00:00\",\"dateModified\":\"2025-11-25T13:49:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/704fb842a150c870ec736ee629ee7e24\"},\"description\":\"Lire les signes 2025 lutte contre la cyberviolence. Apprenez \u00e0 rep\u00e9rer, pr\u00e9venir et agir. Ensemble, nous pouvons rendre le monde num\u00e9rique s\u00fbr pour les femmes et les filles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/RTS-2024-Banner-FR-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/RTS-2024-Banner-FR-scaled.png\",\"width\":2560,\"height\":1054},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/read-the-signs-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;READ THE SIGNS&#8221; 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/\",\"name\":\"Soroptimist\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#\\\/schema\\\/person\\\/704fb842a150c870ec736ee629ee7e24\",\"name\":\"Soroptimist\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/author\\\/soropadmin2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"READ THE SIGNS\" 2025 - Soroptimist","description":"Lire les signes 2025 lutte contre la cyberviolence. Apprenez \u00e0 rep\u00e9rer, pr\u00e9venir et agir. Ensemble, nous pouvons rendre le monde num\u00e9rique s\u00fbr pour les femmes et les filles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"\"READ THE SIGNS\" 2025 - Soroptimist","og_description":"Lire les signes 2025 lutte contre la cyberviolence. Apprenez \u00e0 rep\u00e9rer, pr\u00e9venir et agir. Ensemble, nous pouvons rendre le monde num\u00e9rique s\u00fbr pour les femmes et les filles.","og_url":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/","og_site_name":"Soroptimist","article_published_time":"2025-10-29T14:33:23+00:00","article_modified_time":"2025-11-25T13:49:02+00:00","og_image":[{"width":2560,"height":1054,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2024-Banner-FR-scaled.png","type":"image\/png"}],"author":"Soroptimist","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Soroptimist","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/#article","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/"},"author":{"name":"Soroptimist","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/704fb842a150c870ec736ee629ee7e24"},"headline":"\u00ab\u00a0READ THE SIGNS\u00a0\u00bb 2025","datePublished":"2025-10-29T14:33:23+00:00","dateModified":"2025-11-25T13:49:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/"},"wordCount":702,"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2024-Banner-FR-scaled.png","keywords":["Eradiquer la violence \u00e0 l'\u00e9gard des femmes","Advocacy"],"articleSection":["Advocacy","Eradiquer la violence \u00e0 l&#039;\u00e9gard des femmes","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/","url":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/","name":"\"READ THE SIGNS\" 2025 - Soroptimist","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2024-Banner-FR-scaled.png","datePublished":"2025-10-29T14:33:23+00:00","dateModified":"2025-11-25T13:49:02+00:00","author":{"@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/704fb842a150c870ec736ee629ee7e24"},"description":"Lire les signes 2025 lutte contre la cyberviolence. Apprenez \u00e0 rep\u00e9rer, pr\u00e9venir et agir. Ensemble, nous pouvons rendre le monde num\u00e9rique s\u00fbr pour les femmes et les filles.","breadcrumb":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/#primaryimage","url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2024-Banner-FR-scaled.png","contentUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2025\/10\/RTS-2024-Banner-FR-scaled.png","width":2560,"height":1054},{"@type":"BreadcrumbList","@id":"https:\/\/www.soroptimisteurope.org\/fr\/read-the-signs-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soroptimisteurope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"&#8220;READ THE SIGNS&#8221; 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.soroptimisteurope.org\/#website","url":"https:\/\/www.soroptimisteurope.org\/","name":"Soroptimist","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soroptimisteurope.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.soroptimisteurope.org\/#\/schema\/person\/704fb842a150c870ec736ee629ee7e24","name":"Soroptimist","url":"https:\/\/www.soroptimisteurope.org\/fr\/author\/soropadmin2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/51348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/comments?post=51348"}],"version-history":[{"count":0,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/posts\/51348\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media\/50991"}],"wp:attachment":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media?parent=51348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/categories?post=51348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/tags?post=51348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}