{"id":22621,"date":"2021-11-29T15:36:53","date_gmt":"2021-11-29T14:36:53","guid":{"rendered":"http:\/\/www.soroptimisteurope.org\/?post_type=projet&#038;p=22621"},"modified":"2025-05-16T12:49:35","modified_gmt":"2025-05-16T10:49:35","slug":"une-boite-pour-lavenir","status":"publish","type":"projet","link":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/","title":{"rendered":"Une bo\u00eete pour l\u2019avenir"},"content":{"rendered":"<p>Tout a commenc\u00e9 dans un refuge avec une jeune femme qui s\u2019est confi\u00e9e au sujet de sa difficile situation. Son histoire, racont\u00e9e \u00e0 l\u2019occasion d\u2019une campagne de sensibilisation sur l\u2019\u00e9radication de la violence \u00e0 l\u2019\u00e9gard des femmes, a permis aux Soroptimist de Scheveningen de comprendre tout ce qu\u2019elles avaient \u00e0 faire.<\/p>\n<p>Les Soroptimist ont d\u00e9couvert que le gouvernement n\u00e9erlandais ne procure que le strict n\u00e9cessaire aux survivantes de violences domestiques\u00a0: de la nourriture et un abri. Comme l\u2019a exprim\u00e9 cette jeune femme, cela ne suffit pas. Elles ont aussi besoin d\u2019une formation pour assurer leur ind\u00e9pendance dans leur vie future.<\/p>\n<p>Avec Stichting Perspektief<strong>,<\/strong> une ONG qui propose des refuges en cas de crise et des services d\u2019aide \u00e0 l\u2019autonomisation, les Soroptimist ont con\u00e7u un programme de formation. Le but de celui-ci \u00e9tait de permettre l\u2019\u00e9mancipation de jeunes femmes de moins de 27\u00a0ans qui vivent dans un refuge \u00e0 La Haye.<\/p>\n<p><strong>La \u00ab\u00a0bo\u00eete pour l\u2019avenir\u00a0\u00bb \u00e9tait n\u00e9e<\/strong><\/p>\n<p>Les Soroptimist ont identifi\u00e9 les formations les plus utiles pour ces jeunes filles. En travaillant avec Stichting Perspektief et la personne responsable du refuge, elles ont donn\u00e9 naissance \u00e0 la \u00ab\u00a0bo\u00eete pour l\u2019avenir\u00a0\u00bb, un programme de formations ax\u00e9 sur les cinq sujets suivants\u00a0:<\/p>\n<ul>\n<li>Autod\u00e9fense<\/li>\n<li>Budg\u00e9tisation<\/li>\n<li>\u00c9ducation des enfants<\/li>\n<li>\u00c9ducation sexuelle<\/li>\n<li>Art-th\u00e9rapie<\/li>\n<\/ul>\n<p>Les femmes participant \u00e0 ces formations pouvaient obtenir plusieurs certificats. Les formations \u00e9taient organis\u00e9es par le refuge et les Soroptimist ont collect\u00e9 3\u00a0200\u00a0EUR pour contribuer \u00e0 leur financement.<\/p>\n<p>Malgr\u00e9 la pand\u00e9mie, 24\u00a0filles ont d\u00e9j\u00e0 b\u00e9n\u00e9fici\u00e9 de ce projet. Les membres du Soroptimist International Scheveningen ont \u00e0 c\u0153ur de faire augmenter ce chiffre en proposant cette opportunit\u00e9 \u00e0 davantage de jeunes femmes.<\/p>\n<p>Elles estiment que ce projet pallie \u00e0 certaines lacunes de la politique gouvernementale. Avec la \u00ab\u00a0bo\u00eete pour l\u2019avenir\u00a0\u00bb, elles jouent un r\u00f4le fondamental pour aider \u00e0 pr\u00e9parer ces jeunes femmes \u00e0 une autonomie compl\u00e8te et \u00e0 une vie sans violence.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tout a commenc\u00e9 dans un refuge avec une jeune femme qui s\u2019est confi\u00e9e au sujet de sa difficile situation. Son histoire, racont\u00e9e \u00e0 l\u2019occasion d\u2019une campagne de sensibilisation sur l\u2019\u00e9radication [&hellip;]<\/p>\n","protected":false},"featured_media":22301,"template":"","categories":[127],"class_list":["post-22621","projet","type-projet","status-publish","has-post-thumbnail","hentry","category-eradiquer-la-violence-a-legard-des-femmes"],"acf":{"projet_autres_projets":false,"projet_documents":false,"projet_femmes_aidees_nombre":"","projet_galerie":false,"projet_temoignage":false,"projet_chapeau":"","projet_pays":"Pays-Bas","projet_ville":"Scheveningen","projet_femmes_aidees_legende":"","projet_argent recolte_montant":"","projet_argent_recolte_legende":"","projet_statut":"project_in_progress","projet_clubs":[{"ID":3753,"post_author":"2","post_date":"2016-11-15 16:25:31","post_date_gmt":"2016-11-15 15:25:31","post_content":"","post_title":"Scheveningen","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"scheveningen","to_ping":"","pinged":"","post_modified":"2016-11-15 16:25:31","post_modified_gmt":"2016-11-15 15:25:31","post_content_filtered":"","post_parent":0,"guid":"http:\/\/www.soroptimisteurope.org\/fr\/?post_type=club&#038;p=3753","menu_order":0,"post_type":"club","post_mime_type":"","comment_count":"0","filter":"raw"}],"projet_theme":{"ID":864,"post_author":"1","post_date":"2016-09-30 10:03:54","post_date_gmt":"2016-09-30 09:03:54","post_content":"Nous menons des projets pour r\u00e9pondre, pr\u00e9venir et \u00e9radiquer la violence \u00e0 l\u2019\u00e9gard des femmes et des filles \u00e0 travers le monde. Nos actions incluent la construction d'abris, l'aide aux victimes de violence, les services de conseils, le lobbying en faveur de l\u2019am\u00e9lioration des programmes et des politiques de pr\u00e9vention, et la sensibilisation.\r\n\r\nUn grand nombre de nos projets dans ce domaine sont men\u00e9s en collaboration avec les gouvernements locaux et nationaux, les d\u00e9cideurs politiques et d'autres organisations \/ institutions qui travaillent en faveur de l'\u00e9radication de la violence \u00e0 l\u2019\u00e9gard les femmes gr\u00e2ce \u00e0 l'am\u00e9lioration des strat\u00e9gies et des programmes de pr\u00e9vention et d'intervention.\r\n\r\nDepuis 2022, durant les 16 jours d'activisme contre la violence bas\u00e9e sur le genre, nous nous concentrons sur la pr\u00e9vention de la violence par le biais de la campagne READ THE SIGNS. En apprenant \u00e0 <strong>\u00ab<a href=\"https:\/\/soroptimist-projects.org\/fr\/read-the-signs\/\" target=\"_blank\" rel=\"noopener\">READ THE SIGNS\u00bb<\/a><\/strong> (lire les signes) des comportements toxiques et agressifs, la victime, mais aussi sa famille, ses amis et ses proches seront arm\u00e9s pour les identifier correctement, prendre les mesures appropri\u00e9es et apporter une aide. En 2023, nous proposons d'aller plus loin en introduisant un \u00e9l\u00e9ment essentiel : la sensibilisation \u00e0 la sant\u00e9 mentale.\r\n\r\nPour plus d'informations, cliquez <strong><a href=\"https:\/\/www.soroptimisteurope.org\/fr\/la-campagne-read-the-signs-innove-en-2023\/\" target=\"_blank\" rel=\"noopener\">ICI<\/a><\/strong>.","post_title":"Violence \u00e0 l'\u00e9gard des femmes","post_excerpt":"Depuis plus d'un si\u00e8cle, les Soroptimist sont engag\u00e9es dans des actions en vue d\u2019\u00e9radiquer la violence envers les femmes et les filles et de garantir la participation des femmes dans la r\u00e9solution des conflits.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"eradiquer-violence-a-legard-femmes","to_ping":"","pinged":"","post_modified":"2023-07-25 14:40:08","post_modified_gmt":"2023-07-25 13:40:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/www.soroptimisteurope.org\/fr\/?post_type=programme&#038;p=864","menu_order":2,"post_type":"programme","post_mime_type":"","comment_count":"0","filter":"raw"},"projet_localisation":{"address":"Scheveningen","lat":52.1024015,"lng":4.3021834,"zoom":14,"place_id":"ChIJZVfFwZewxUcRDeGY9F3LwTE","city":"La Haye","state":"Hollande-M\u00e9ridionale","state_short":"ZH","country":"Pays-Bas","country_short":"NL"}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une bo\u00eete pour l\u2019avenir - Soroptimist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une bo\u00eete pour l\u2019avenir - Soroptimist\" \/>\n<meta property=\"og:description\" content=\"Tout a commenc\u00e9 dans un refuge avec une jeune femme qui s\u2019est confi\u00e9e au sujet de sa difficile situation. Son histoire, racont\u00e9e \u00e0 l\u2019occasion d\u2019une campagne de sensibilisation sur l\u2019\u00e9radication [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/\" \/>\n<meta property=\"og:site_name\" content=\"Soroptimist\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-16T10:49:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/11\/istock-1212830670.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/nos-projets\\\/une-boite-pour-lavenir\\\/\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/nos-projets\\\/une-boite-pour-lavenir\\\/\",\"name\":\"Une bo\u00eete pour l\u2019avenir - Soroptimist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/nos-projets\\\/une-boite-pour-lavenir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/nos-projets\\\/une-boite-pour-lavenir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/istock-1212830670.jpg\",\"datePublished\":\"2021-11-29T14:36:53+00:00\",\"dateModified\":\"2025-05-16T10:49:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/nos-projets\\\/une-boite-pour-lavenir\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/nos-projets\\\/une-boite-pour-lavenir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/nos-projets\\\/une-boite-pour-lavenir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/istock-1212830670.jpg\",\"contentUrl\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/istock-1212830670.jpg\",\"width\":2121,\"height\":1414,\"caption\":\"Woman gestures while discussing something difficult during a support group or group therapy session. A mental health professional is taking notes in the background. People at group psychotherapy session indoors\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/nos-projets\\\/une-boite-pour-lavenir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une bo\u00eete pour l\u2019avenir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/#website\",\"url\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/\",\"name\":\"Soroptimist\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.soroptimisteurope.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une bo\u00eete pour l\u2019avenir - Soroptimist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/","og_locale":"fr_FR","og_type":"article","og_title":"Une bo\u00eete pour l\u2019avenir - Soroptimist","og_description":"Tout a commenc\u00e9 dans un refuge avec une jeune femme qui s\u2019est confi\u00e9e au sujet de sa difficile situation. Son histoire, racont\u00e9e \u00e0 l\u2019occasion d\u2019une campagne de sensibilisation sur l\u2019\u00e9radication [&hellip;]","og_url":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/","og_site_name":"Soroptimist","article_modified_time":"2025-05-16T10:49:35+00:00","og_image":[{"width":2121,"height":1414,"url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/11\/istock-1212830670.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/","url":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/","name":"Une bo\u00eete pour l\u2019avenir - Soroptimist","isPartOf":{"@id":"https:\/\/www.soroptimisteurope.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/#primaryimage"},"image":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/#primaryimage"},"thumbnailUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/11\/istock-1212830670.jpg","datePublished":"2021-11-29T14:36:53+00:00","dateModified":"2025-05-16T10:49:35+00:00","breadcrumb":{"@id":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/#primaryimage","url":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/11\/istock-1212830670.jpg","contentUrl":"https:\/\/www.soroptimisteurope.org\/wp-content\/uploads\/2021\/11\/istock-1212830670.jpg","width":2121,"height":1414,"caption":"Woman gestures while discussing something difficult during a support group or group therapy session. A mental health professional is taking notes in the background. People at group psychotherapy session indoors"},{"@type":"BreadcrumbList","@id":"https:\/\/www.soroptimisteurope.org\/fr\/nos-projets\/une-boite-pour-lavenir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.soroptimisteurope.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Une bo\u00eete pour l\u2019avenir"}]},{"@type":"WebSite","@id":"https:\/\/www.soroptimisteurope.org\/#website","url":"https:\/\/www.soroptimisteurope.org\/","name":"Soroptimist","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.soroptimisteurope.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/projet\/22621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/projet"}],"about":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/types\/projet"}],"version-history":[{"count":0,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/projet\/22621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media\/22301"}],"wp:attachment":[{"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/media?parent=22621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soroptimisteurope.org\/fr\/wp-json\/wp\/v2\/categories?post=22621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}